{"id":403,"date":"2022-08-25T21:29:06","date_gmt":"2022-08-25T21:29:06","guid":{"rendered":"https:\/\/workmimarlik.com\/?post_type=portfolio&#038;p=403"},"modified":"2022-12-13T07:47:33","modified_gmt":"2022-12-13T07:47:33","slug":"vela-dekor","status":"publish","type":"portfolio","link":"https:\/\/workmimarlik.com\/tr\/portfolio\/vela-dekor\/","title":{"rendered":"Vela Dekor"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"403\" class=\"elementor elementor-403\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5fdfcfc0 elementor-section-stretched elementor-section-height-min-height elementor-section-boxed elementor-section-height-default elementor-section-items-middle\" data-id=\"5fdfcfc0\" data-element_type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"aux-parallax-section elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-14068361 aux-appear-watch-animation aux-fade-in-right\" data-id=\"14068361\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3c9807fe elementor-widget elementor-widget-aux_modern_heading\" data-id=\"3c9807fe\" data-element_type=\"widget\" data-widget_type=\"aux_modern_heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<section class=\"aux-widget-modern-heading\">\n            <div class=\"aux-widget-inner\"><h2 class=\"aux-modern-heading-primary\">Projelerimiz<\/h2><\/div>\n        <\/section>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-295863e elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"295863e\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"aux-parallax-section elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-ed4b3b2\" data-id=\"ed4b3b2\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f5abbef elementor-widget elementor-widget-eg_image_gallery\" data-id=\"f5abbef\" data-element_type=\"widget\" data-widget_type=\"eg_image_gallery.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"jeg_preview_slider slider_light jeg_module___6a04bfb429415\" data-selector='jeg_module___6a04bfb429415'>\n                    <div class=\"jeg_preview_holder\">\n                        <div class=\"jeg_preview_media\">\n                    <div class=\"jeg_preview_media_holder\">\n                        <h3><\/h3>\n                        <div class=\"fullscreen-switch\">\n                            <i class=\"fa\"><\/i>\n                        <\/div>\n                        <div class=\"jeg_preview_media_content\">\n                            <div class=\"jeg_preview_media_content_holder_padding\">\n                                <div class=\"jeg_preview_media_content_holder\"><\/div>\n                            <\/div>\n                            <div class=\"jeg_preview_media_content_navigation\">\n                                <div class=\"prev\"><\/div>\n                                <div class=\"next\"><\/div>\n                            <\/div>\n                            <div class='preview-slider-overlay'>\n                                <div class='preloader_type preloader_dot'>\n                                    <div class=\"module-preloader jeg_preloader dot\">\n                                        <span><\/span><span><\/span><span><\/span>\n                                    <\/div>\n                                    <div class=\"module-preloader jeg_preloader circle\">\n                                        <div class=\"jeg_preloader_circle_outer\">\n                                            <div class=\"jeg_preloader_circle_inner\"><\/div>\n                                        <\/div>\n                                    <\/div>\n                                    <div class=\"module-preloader jeg_preloader square\">\n                                        <div class=\"jeg-cube-grid\">\n                                            <div class=\"jeg-cube jeg-cube1\"><\/div>\n                                            <div class=\"jeg-cube jeg-cube2\"><\/div>\n                                            <div class=\"jeg-cube jeg-cube3\"><\/div>\n                                            <div class=\"jeg-cube jeg-cube4\"><\/div>\n                                          <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div>\n                        <\/div>\n                        <div class=\"jeg_preview_control\">\n                            <div class=\"left_control\">\n                                <div class=\"counter\"><span class=\"current\">1<\/span> of  4<\/div>\n                                <div class=\"subtitle\"><\/div>\n                            <\/div>\n                            <div class=\"zoom\">\n                                <span class=\"reduce\">-<\/span>\n                                <span class=\"increase\">+<\/span>\n                            <\/div>\n                        <\/div>\n                    <\/div>\n                <\/div>\n\n                <div class=\"jeg_preview_bottom_slider owl-carousel\">\n                    <a data-id=\"0\" data-title=\"\" data-image=\"https:\/\/workmimarlik.com\/wp-content\/uploads\/2022\/08\/work-mimarlik-projelerimiz-vela-dekor-1.jpg\" href=\"https:\/\/workmimarlik.com\/wp-content\/uploads\/2022\/08\/work-mimarlik-projelerimiz-vela-dekor-1.jpg\" class=\"jeg_preview_item active\">\n                        <div class=\"jeg_preview_item_thumbnail\">\n                            <img decoding=\"async\" width=\"120\" height=\"86\" src=\"https:\/\/workmimarlik.com\/wp-content\/uploads\/2022\/08\/work-mimarlik-projelerimiz-vela-dekor-1-120x86.jpg\" class=\"attachment-jeg-120x86 size-jeg-120x86\" alt=\"\" srcset=\"https:\/\/workmimarlik.com\/wp-content\/uploads\/2022\/08\/work-mimarlik-projelerimiz-vela-dekor-1-120x86.jpg 120w, https:\/\/workmimarlik.com\/wp-content\/uploads\/2022\/08\/work-mimarlik-projelerimiz-vela-dekor-1-1536x1085.jpg 1536w, https:\/\/workmimarlik.com\/wp-content\/uploads\/2022\/08\/work-mimarlik-projelerimiz-vela-dekor-1.jpg 1600w\" sizes=\"(max-width: 120px) 100vw, 120px\" \/>\n                        <\/div>\n                    <\/a><a data-id=\"1\" data-title=\"\" data-image=\"https:\/\/workmimarlik.com\/wp-content\/uploads\/2022\/12\/vela-1.jpg\" href=\"https:\/\/workmimarlik.com\/wp-content\/uploads\/2022\/12\/vela-1.jpg\" class=\"jeg_preview_item \">\n                        <div class=\"jeg_preview_item_thumbnail\">\n                            <img decoding=\"async\" width=\"120\" height=\"86\" src=\"https:\/\/workmimarlik.com\/wp-content\/uploads\/2022\/12\/vela-1-120x86.jpg\" class=\"attachment-jeg-120x86 size-jeg-120x86\" alt=\"\" srcset=\"https:\/\/workmimarlik.com\/wp-content\/uploads\/2022\/12\/vela-1-120x86.jpg 120w, https:\/\/workmimarlik.com\/wp-content\/uploads\/2022\/12\/vela-1-1536x1085.jpg 1536w, https:\/\/workmimarlik.com\/wp-content\/uploads\/2022\/12\/vela-1-18x12.jpg 18w, https:\/\/workmimarlik.com\/wp-content\/uploads\/2022\/12\/vela-1.jpg 1600w\" sizes=\"(max-width: 120px) 100vw, 120px\" \/>\n                        <\/div>\n                    <\/a><a data-id=\"2\" data-title=\"\" data-image=\"https:\/\/workmimarlik.com\/wp-content\/uploads\/2022\/12\/vela-2.jpg\" href=\"https:\/\/workmimarlik.com\/wp-content\/uploads\/2022\/12\/vela-2.jpg\" class=\"jeg_preview_item \">\n                        <div class=\"jeg_preview_item_thumbnail\">\n                            <img decoding=\"async\" width=\"120\" height=\"86\" src=\"https:\/\/workmimarlik.com\/wp-content\/uploads\/2022\/12\/vela-2-120x86.jpg\" class=\"attachment-jeg-120x86 size-jeg-120x86\" alt=\"\" srcset=\"https:\/\/workmimarlik.com\/wp-content\/uploads\/2022\/12\/vela-2-120x86.jpg 120w, https:\/\/workmimarlik.com\/wp-content\/uploads\/2022\/12\/vela-2-1536x1085.jpg 1536w, https:\/\/workmimarlik.com\/wp-content\/uploads\/2022\/12\/vela-2-18x12.jpg 18w, https:\/\/workmimarlik.com\/wp-content\/uploads\/2022\/12\/vela-2.jpg 1600w\" sizes=\"(max-width: 120px) 100vw, 120px\" \/>\n                        <\/div>\n                    <\/a><a data-id=\"3\" data-title=\"\" data-image=\"https:\/\/workmimarlik.com\/wp-content\/uploads\/2022\/12\/vela-3.jpg\" href=\"https:\/\/workmimarlik.com\/wp-content\/uploads\/2022\/12\/vela-3.jpg\" class=\"jeg_preview_item \">\n                        <div class=\"jeg_preview_item_thumbnail\">\n                            <img loading=\"lazy\" decoding=\"async\" width=\"120\" height=\"86\" src=\"https:\/\/workmimarlik.com\/wp-content\/uploads\/2022\/12\/vela-3-120x86.jpg\" class=\"attachment-jeg-120x86 size-jeg-120x86\" alt=\"\" srcset=\"https:\/\/workmimarlik.com\/wp-content\/uploads\/2022\/12\/vela-3-120x86.jpg 120w, https:\/\/workmimarlik.com\/wp-content\/uploads\/2022\/12\/vela-3-1536x1085.jpg 1536w, https:\/\/workmimarlik.com\/wp-content\/uploads\/2022\/12\/vela-3-18x12.jpg 18w, https:\/\/workmimarlik.com\/wp-content\/uploads\/2022\/12\/vela-3.jpg 1600w\" sizes=\"(max-width: 120px) 100vw, 120px\" \/>\n                        <\/div>\n                    <\/a>\n                <\/div>\n                    <\/div>\n                    <div class=\"jeg_preview_description\">\n                        \n                        <div class=\"jeg_preview_description_wrapper\">\n                        \n                        <\/div>\n                    <\/div>\n                    <script>\n                        var jeg_module___6a04bfb429415 = {\n                            rtl: false,\n                            native_zoom: false,\n                            zoom_max: 5,\n                            zoom_step: 40,\n                            image_sequence: [{\"src\":\"https:\\\/\\\/workmimarlik.com\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/work-mimarlik-projelerimiz-vela-dekor-1.jpg\",\"w\":1600,\"h\":1130,\"title\":\"\"},{\"src\":\"https:\\\/\\\/workmimarlik.com\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/vela-1.jpg\",\"w\":1600,\"h\":1130,\"title\":\"\"},{\"src\":\"https:\\\/\\\/workmimarlik.com\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/vela-2.jpg\",\"w\":1600,\"h\":1130,\"title\":\"\"},{\"src\":\"https:\\\/\\\/workmimarlik.com\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/vela-3.jpg\",\"w\":1600,\"h\":1130,\"title\":\"\"}]\n                        };\n                    <\/script>\n                <\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"aux-parallax-section elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-3d6cd41\" data-id=\"3d6cd41\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e61922a elementor-widget elementor-widget-aux_post_title\" data-id=\"e61922a\" data-element_type=\"widget\" data-widget_type=\"aux_post_title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h1 class=\"entry-title\">Vela Dekor<\/h1>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e22d452 elementor-widget elementor-widget-aux_icon_list\" data-id=\"e22d452\" data-element_type=\"widget\" data-widget_type=\"aux_icon_list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<section class=\"widget-container aux-widget-icon-list aux-parent-au0f19f413\" style=\"\" ><div class=\"widget-inner\"><div class=\"aux-widget-icon-list-inner\"><ul class=\"aux-icon-list-items aux-direction-vertical\" ><li class=\"aux-icon-list-item aux-list-item-has-icon aux-icon-list-item-5c2160c elementor-repeater-item-5c2160c\" ><span class=\"aux-icon-list-text\" >Ah\u015fap Fuar Stand\u0131<\/span><\/li><li class=\"aux-icon-list-item aux-list-item-has-icon aux-icon-list-item-77dc124 elementor-repeater-item-77dc124\" ><span class=\"aux-icon-list-icon far fa-clock\" ><\/span><span class=\"aux-icon-list-text\" >BA\u015eLAMA:<\/span><span class=\"aux-icon-list-text2\" >12 Kas\u0131m 2022<\/span><\/li><li class=\"aux-icon-list-item aux-list-item-has-icon aux-icon-list-item-063cb10 elementor-repeater-item-063cb10\" ><span class=\"aux-icon-list-icon auxicon auxicon-clock-4\" ><\/span><span class=\"aux-icon-list-text\" >B\u0130T\u0130\u015e:<\/span><span class=\"aux-icon-list-text2\" >16 Kas\u0131m 2022<\/span><\/li><li class=\"aux-icon-list-item aux-list-item-has-icon aux-icon-list-item-63d5ccd elementor-repeater-item-63d5ccd\" ><span class=\"aux-icon-list-icon auxicon auxicon-location-2\" ><\/span><span class=\"aux-icon-list-text\" >YER:<\/span><span class=\"aux-icon-list-text2\" >Kap\u0131 ve Pencere Fuar\u0131<\/span><\/li><\/ul><\/div><\/div><\/section><!-- widget-container -->\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-509596f7 elementor-section-stretched elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"509596f7\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;stretch_section&quot;:&quot;section-stretched&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"aux-parallax-section elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-89d63cd\" data-id=\"89d63cd\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6079b9b4 aux-appear-watch-animation aux-scale-down elementor-widget elementor-widget-aux_modern_heading\" data-id=\"6079b9b4\" data-element_type=\"widget\" data-widget_type=\"aux_modern_heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<section class=\"aux-widget-modern-heading\">\n            <div class=\"aux-widget-inner\"><h2 class=\"aux-modern-heading-primary\">Bizimle \u00e7al\u0131\u015fmak ister misiniz?<\/h2><div class=\"aux-modern-heading-description\"><p>Bizimle \u00e7al\u0131\u015fmak, ailemizin bir par\u00e7as\u0131 ve ihtiya\u00e7lar\u0131n\u0131za \u00f6zel \u00e7\u00f6z\u00fcmler \u00fcretmemiz i\u00e7in diledi\u011finiz zaman bizimle ileti\u015fime ge\u00e7ebilir ve detayl\u0131 bilgi alabilirsiniz.<\/p><\/div><\/div>\n        <\/section>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-bfff39b elementor-widget elementor-widget-aux_modern_button\" data-id=\"bfff39b\" data-element_type=\"widget\" data-widget_type=\"aux_modern_button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t    <div class=\"aux-modern-button-wrapper aux-modern-button-align-center\" >\n                    <a class=\"aux-modern-button aux-white aux-modern-button-xl aux-modern-button-normal aux-modern-button-default aux-icon-right\" href=\"\/iletisim\">\n                <div class=\"aux-overlay\"><\/div>\n                                    <div class=\"aux-icon \">\n                        <i aria-hidden=\"true\" class=\"auxicon2 auxicon2-arrow-chevron-small-right\"><\/i>                    <\/div>\n                                <div class=\"aux-text\">\n<span class=\"aux-text-before\">\u0130LET\u0130\u015e\u0130ME GE\u00c7<\/span>                <\/div>\n            <\/a>\n            \n    <\/div>\n\n    \t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Projelerimiz 1 of 4 &#8211; + Vela Dekor Ah\u015fap Fuar Stand\u0131 BA\u015eLAMA:12 Kas\u0131m 2022 B\u0130T\u0130\u015e:16 Kas\u0131m 2022 YER:Kap\u0131 ve Pencere Fuar\u0131 Bizimle \u00e7al\u0131\u015fmak ister misiniz? Bizimle \u00e7al\u0131\u015fmak, ailemizin bir par\u00e7as\u0131 ve ihtiya\u00e7lar\u0131n\u0131za \u00f6zel \u00e7\u00f6z\u00fcmler \u00fcretmemiz i\u00e7in diledi\u011finiz zaman bizimle ileti\u015fime ge\u00e7ebilir ve detayl\u0131 bilgi alabilirsiniz. \u0130LET\u0130\u015e\u0130ME GE\u00c7<\/p>\n","protected":false},"featured_media":872,"menu_order":0,"template":"","meta":{"footnotes":""},"portfolio-cat":[15],"portfolio-tag":[13],"portfolio-filter":[14],"class_list":["post-403","portfolio","type-portfolio","status-publish","has-post-thumbnail","hentry","portfolio-cat-ahsap-fuar-standi","portfolio-tag-uncategorized","portfolio-filter-uncategorized"],"_links":{"self":[{"href":"https:\/\/workmimarlik.com\/tr\/wp-json\/wp\/v2\/portfolio\/403","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/workmimarlik.com\/tr\/wp-json\/wp\/v2\/portfolio"}],"about":[{"href":"https:\/\/workmimarlik.com\/tr\/wp-json\/wp\/v2\/types\/portfolio"}],"version-history":[{"count":25,"href":"https:\/\/workmimarlik.com\/tr\/wp-json\/wp\/v2\/portfolio\/403\/revisions"}],"predecessor-version":[{"id":878,"href":"https:\/\/workmimarlik.com\/tr\/wp-json\/wp\/v2\/portfolio\/403\/revisions\/878"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/workmimarlik.com\/tr\/wp-json\/wp\/v2\/media\/872"}],"wp:attachment":[{"href":"https:\/\/workmimarlik.com\/tr\/wp-json\/wp\/v2\/media?parent=403"}],"wp:term":[{"taxonomy":"portfolio-cat","embeddable":true,"href":"https:\/\/workmimarlik.com\/tr\/wp-json\/wp\/v2\/portfolio-cat?post=403"},{"taxonomy":"portfolio-tag","embeddable":true,"href":"https:\/\/workmimarlik.com\/tr\/wp-json\/wp\/v2\/portfolio-tag?post=403"},{"taxonomy":"portfolio-filter","embeddable":true,"href":"https:\/\/workmimarlik.com\/tr\/wp-json\/wp\/v2\/portfolio-filter?post=403"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}