{"id":69,"date":"2018-06-19T10:45:31","date_gmt":"2018-06-19T10:45:31","guid":{"rendered":"https:\/\/workmimarlik.com\/?page_id=69"},"modified":"2023-03-15T10:06:37","modified_gmt":"2023-03-15T10:06:37","slug":"projelerimiz","status":"publish","type":"page","link":"https:\/\/workmimarlik.com\/tr\/projelerimiz\/","title":{"rendered":"Projelerimiz"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"69\" class=\"elementor elementor-69\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-73f19eb elementor-section-stretched elementor-section-height-min-height elementor-section-boxed elementor-section-height-default elementor-section-items-middle\" data-id=\"73f19eb\" data-element_type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"aux-parallax-section elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-2f5d6eb aux-appear-watch-animation aux-fade-in-right\" data-id=\"2f5d6eb\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-59a1228 elementor-widget elementor-widget-aux_modern_heading\" data-id=\"59a1228\" data-element_type=\"widget\" data-widget_type=\"aux_modern_heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<section class=\"aux-widget-modern-heading\">\n            <div class=\"aux-widget-inner\"><h2 class=\"aux-modern-heading-primary\">Projelerimiz<\/h2><\/div>\n        <\/section>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-749adada elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"749adada\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"aux-parallax-section elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-69dbfc3f\" data-id=\"69dbfc3f\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-4b63b8b9 aux-appear-watch-animation aux-fade-in-up elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"4b63b8b9\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"aux-parallax-section elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-d3536a\" data-id=\"d3536a\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7c7fbc54 elementor-widget elementor-widget-aux_modern_heading\" data-id=\"7c7fbc54\" data-element_type=\"widget\" data-widget_type=\"aux_modern_heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<section class=\"aux-widget-modern-heading\">\n            <div class=\"aux-widget-inner\"><h2 class=\"aux-modern-heading-primary\">WORK M\u0130MARLIK<\/h2><h3 class=\"aux-modern-heading-secondary\"><span class=\"aux-head-before\">Tamamlanan Projelerimiz<\/span><\/h3><div class=\"aux-modern-heading-divider\"><\/div><\/div>\n        <\/section>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"aux-parallax-section elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-2404318c\" data-id=\"2404318c\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7fd7456 elementor-widget elementor-widget-heading\" data-id=\"7fd7456\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Referanslar\u0131m\u0131z\u0131n aras\u0131na kat\u0131lmak ve onlarca ba\u015far\u0131l\u0131 projeden birine sahip olmak i\u00e7in bizimle ileti\u015fime ge\u00e7ebilirsiniz.<\/p>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-9646ec5 aux-appear-watch-animation aux-fade-in-up elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"9646ec5\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"aux-parallax-section elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-81051d2\" data-id=\"81051d2\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3b7b21f aux-arch-home-port elementor-widget elementor-widget-aux_recent_portfolios_grid\" data-id=\"3b7b21f\" data-element_type=\"widget\" data-settings=\"{&quot;columns_tablet&quot;:&quot;2&quot;,&quot;columns&quot;:&quot;3&quot;,&quot;columns_mobile&quot;:&quot;1&quot;}\" data-widget_type=\"aux_recent_portfolios_grid.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<section class=\"widget-container aux-widget-recent-portfolios aux-parent-auabc3e781\" style=\"\" ><div class=\"aux-filters aux-togglable aux-overlay aux-underline-anim aux-center aux-ajax-filters\"><div class=\"aux-select-overlay\"><\/div><ul><li data-filter=\"ahsap-fuar-standi\" data-category-id=\"15\" ><a href=\"#\"><span data-select=\"Ah\u015fap Fuar Stand\u0131\">Ah\u015fap Fuar Stand\u0131<\/span><\/a><\/li><li data-filter=\"maxima-fuar-standi\" data-category-id=\"16\" ><a href=\"#\"><span data-select=\"Maxima Fuar Stand\u0131\">Maxima Fuar Stand\u0131<\/span><\/a><\/li><li data-filter=\"moduler-fuar-standi\" data-category-id=\"18\" ><a href=\"#\"><span data-select=\"Mod\u00fcler Fuar Stand\u0131\">Mod\u00fcler Fuar Stand\u0131<\/span><\/a><\/li><\/ul><\/div><div id=\"6a04cdf453a4a\" data-element-id=\"auabc3e781\" class=\"aux-portfolio-columns aux-ajax-view aux-isotope-animated aux-isotope-layout aux-layout-grid aux-no-gutter aux-row aux-match-height aux-de-col3 aux-tb-col2 aux-mb-col1 aux-lightbox-gallery\" data-lazyload=\"true\" data-space=\"30\" data-pagination=\"true\" data-deeplink=\"true\" data-slug=\"\" data-perpage=\"1000\" data-layout=\"fitRows\" data-reveal-transition-duration=\"600\" data-reveal-between-delay=\"60\" data-hide-transition-duration=\"600\" data-hide-between-delay=\"30\" data-num=\"100\" data-order=\"ASC\" data-orderby=\"date\" data-taxonomy=\"portfolio-cat\" data-n=\"9a557d3bce\"><div class=\"aux-items-loading aux-loading-hide\"><div class=\"aux-loading-loop\"><svg class=\"aux-circle\" width=\"100%\" height=\"100%\" viewBox=\"0 0 42 42\"><circle class=\"aux-stroke-bg\" r=\"20\" cx=\"21\" cy=\"21\" fill=\"none\"><\/circle><circle class=\"aux-progress\" r=\"20\" cx=\"21\" cy=\"21\" fill=\"none\" transform=\"rotate(-90 21 21)\"><\/circle><\/svg><\/div><\/div><div class=\"aux-iso-item aux-loading aux-col\">                         <article class=\"aux-item-overlay aux-hover-active aux-hover-twoway  post-380 portfolio type-portfolio status-publish has-post-thumbnail hentry portfolio-cat-ahsap-fuar-standi portfolio-tag-uncategorized portfolio-filter-uncategorized\" >\n                                <div class=\"entry-media aux-frame-boxed-darken aux-frame-zoom \">\n                                    <div class=\"aux-media-frame aux-media-image\"><a href=\"https:\/\/workmimarlik.com\/tr\/portfolio\/gapsan-pazarlama\/\"><img fetchpriority=\"high\" width=\"606\" height=\"455\" class=\"aux-attachment aux-featured-image attachment-606.66666666667x455 aux-attachment-id-384 \" alt=\"work-mimarlik-projelerimiz-gapsan-pazarlama (5)\" data-ratio=\"1.33\" data-original-w=\"1600\" sizes=\"auto\" data-srcset=\"https:\/\/workmimarlik.com\/wp-content\/uploads\/2022\/08\/work-mimarlik-projelerimiz-gapsan-pazarlama-5-150x113.jpg 150w,https:\/\/workmimarlik.com\/wp-content\/uploads\/2022\/08\/work-mimarlik-projelerimiz-gapsan-pazarlama-5-300x225.jpg 300w,https:\/\/workmimarlik.com\/wp-content\/uploads\/2022\/08\/work-mimarlik-projelerimiz-gapsan-pazarlama-5-768x576.jpg 768w,https:\/\/workmimarlik.com\/wp-content\/uploads\/2022\/08\/work-mimarlik-projelerimiz-gapsan-pazarlama-5-1024x768.jpg 1024w,https:\/\/workmimarlik.com\/wp-content\/uploads\/2022\/08\/work-mimarlik-projelerimiz-gapsan-pazarlama-5-607x455.jpg 607w,https:\/\/workmimarlik.com\/wp-content\/uploads\/2022\/08\/work-mimarlik-projelerimiz-gapsan-pazarlama-5-1590x1192.jpg 1590w\" data-src=\"https:\/\/workmimarlik.com\/wp-content\/uploads\/2022\/08\/work-mimarlik-projelerimiz-gapsan-pazarlama-5-607x455.jpg\" \/><\/a><\/div>                                <\/div>\n\n                                <div class=\"aux-overlay-content\">\n                                                                        <div class=\"aux-portfolio-overlay-buttons\">\n                                        <div class=\"aux-hover-circle-plus aux-delay-2x\">\n                                            <a href=\"https:\/\/workmimarlik.com\/wp-content\/uploads\/2022\/08\/work-mimarlik-projelerimiz-gapsan-pazarlama-5.jpg\" data-elementor-open-lightbox = \"no\" data-original-width = \"1600\" data-original-height = \"1200\" data-caption = \"work-mimarlik-projelerimiz-gapsan-pazarlama (5)\" class=\"aux-lightbox-btn \" >\n                                                <div class=\"aux-arrow-nav aux-round aux-hover-slide aux-outline aux-semi-small aux-white\">\n                                                    <span class=\"aux-overlay\"><\/span>\n                                                    <span class=\"aux-svg-arrow aux-medium-plus aux-white\"><\/span>\n                                                    <span class=\"aux-hover-arrow aux-svg-arrow aux-medium-plus aux-black\"><\/span>\n                                                <\/div>\n                                            <\/a>\n                                        <\/div>\n                                        <div class=\"aux-arrow-post-link aux-hover-circle-link\">\n                                            <a href=\"https:\/\/workmimarlik.com\/tr\/portfolio\/gapsan-pazarlama\/\">\n                                                <div class=\"aux-arrow-nav aux-round aux-hover-slide aux-outline aux-semi-small aux-white\">\n                                                    <span class=\"aux-overlay\"><\/span>\n                                                    <span class=\"aux-svg-arrow aux-medium-right aux-white\"><\/span>\n                                                    <span class=\"aux-hover-arrow aux-svg-arrow aux-medium-right aux-black\"><\/span>\n                                                <\/div>\n                                            <\/a>\n                                        <\/div>\n\n                                    <\/div>\n                                                                                                            <div class=\"entry-main\">\n\n                                                                        <header class=\"entry-header\">\n                                        <h3 class=\"entry-title aux-hover-move-up\">\n                                            <a href=\"https:\/\/workmimarlik.com\/tr\/portfolio\/gapsan-pazarlama\/\">\n                                                Gapsan Pazarlama                                            <\/a>\n                                        <\/h3>\n                                    <\/header>\n                                                                                                            <div class=\"entry-info aux-hover-move-up aux-delay-1x\">\n                                        <span class=\"entry-tax\">\n                                                                                        <a href=\"https:\/\/workmimarlik.com\/tr\/portfolio-cat\/ahsap-fuar-standi\/\" title=\"View all posts in Ah\u015fap Fuar Stand\u0131\" rel=\"category\" >Ah\u015fap Fuar Stand\u0131<\/a>                                        <\/span>\n                                    <\/div>\n                                                                                                            <\/div>\n                                                                <\/div>\n                        <\/article>\n<\/div><div class=\"aux-iso-item aux-loading aux-col\">                         <article class=\"aux-item-overlay aux-hover-active aux-hover-twoway  post-403 portfolio type-portfolio status-publish has-post-thumbnail hentry portfolio-cat-ahsap-fuar-standi portfolio-tag-uncategorized portfolio-filter-uncategorized\" >\n                                <div class=\"entry-media aux-frame-boxed-darken aux-frame-zoom \">\n                                    <div class=\"aux-media-frame aux-media-image\"><a href=\"https:\/\/workmimarlik.com\/tr\/portfolio\/vela-dekor\/\"><img width=\"606\" height=\"455\" class=\"aux-attachment aux-featured-image attachment-606.66666666667x455 aux-attachment-id-872 \" alt=\"vela-2\" data-ratio=\"1.33\" data-original-w=\"1600\" sizes=\"auto\" data-srcset=\"https:\/\/workmimarlik.com\/wp-content\/uploads\/2022\/12\/vela-2-150x113.jpg 150w,https:\/\/workmimarlik.com\/wp-content\/uploads\/2022\/12\/vela-2-300x225.jpg 300w,https:\/\/workmimarlik.com\/wp-content\/uploads\/2022\/12\/vela-2-768x576.jpg 768w,https:\/\/workmimarlik.com\/wp-content\/uploads\/2022\/12\/vela-2-1024x768.jpg 1024w,https:\/\/workmimarlik.com\/wp-content\/uploads\/2022\/12\/vela-2-607x455.jpg 607w,https:\/\/workmimarlik.com\/wp-content\/uploads\/2022\/12\/vela-2-1590x1192.jpg 1590w\" data-src=\"https:\/\/workmimarlik.com\/wp-content\/uploads\/2022\/12\/vela-2-607x455.jpg\" \/><\/a><\/div>                                <\/div>\n\n                                <div class=\"aux-overlay-content\">\n                                                                        <div class=\"aux-portfolio-overlay-buttons\">\n                                        <div class=\"aux-hover-circle-plus aux-delay-2x\">\n                                            <a href=\"https:\/\/workmimarlik.com\/wp-content\/uploads\/2022\/12\/vela-2.jpg\" data-elementor-open-lightbox = \"no\" data-original-width = \"1600\" data-original-height = \"1130\" data-caption = \"vela-2\" class=\"aux-lightbox-btn \" >\n                                                <div class=\"aux-arrow-nav aux-round aux-hover-slide aux-outline aux-semi-small aux-white\">\n                                                    <span class=\"aux-overlay\"><\/span>\n                                                    <span class=\"aux-svg-arrow aux-medium-plus aux-white\"><\/span>\n                                                    <span class=\"aux-hover-arrow aux-svg-arrow aux-medium-plus aux-black\"><\/span>\n                                                <\/div>\n                                            <\/a>\n                                        <\/div>\n                                        <div class=\"aux-arrow-post-link aux-hover-circle-link\">\n                                            <a href=\"https:\/\/workmimarlik.com\/tr\/portfolio\/vela-dekor\/\">\n                                                <div class=\"aux-arrow-nav aux-round aux-hover-slide aux-outline aux-semi-small aux-white\">\n                                                    <span class=\"aux-overlay\"><\/span>\n                                                    <span class=\"aux-svg-arrow aux-medium-right aux-white\"><\/span>\n                                                    <span class=\"aux-hover-arrow aux-svg-arrow aux-medium-right aux-black\"><\/span>\n                                                <\/div>\n                                            <\/a>\n                                        <\/div>\n\n                                    <\/div>\n                                                                                                            <div class=\"entry-main\">\n\n                                                                        <header class=\"entry-header\">\n                                        <h3 class=\"entry-title aux-hover-move-up\">\n                                            <a href=\"https:\/\/workmimarlik.com\/tr\/portfolio\/vela-dekor\/\">\n                                                Vela Dekor                                            <\/a>\n                                        <\/h3>\n                                    <\/header>\n                                                                                                            <div class=\"entry-info aux-hover-move-up aux-delay-1x\">\n                                        <span class=\"entry-tax\">\n                                                                                        <a href=\"https:\/\/workmimarlik.com\/tr\/portfolio-cat\/ahsap-fuar-standi\/\" title=\"View all posts in Ah\u015fap Fuar Stand\u0131\" rel=\"category\" >Ah\u015fap Fuar Stand\u0131<\/a>                                        <\/span>\n                                    <\/div>\n                                                                                                            <\/div>\n                                                                <\/div>\n                        <\/article>\n<\/div><div class=\"aux-iso-item aux-loading aux-col\">                         <article class=\"aux-item-overlay aux-hover-active aux-hover-twoway  post-615 portfolio type-portfolio status-publish has-post-thumbnail hentry portfolio-cat-ahsap-fuar-standi portfolio-tag-uncategorized portfolio-filter-uncategorized\" >\n                                <div class=\"entry-media aux-frame-boxed-darken aux-frame-zoom \">\n                                    <div class=\"aux-media-frame aux-media-image\"><a href=\"https:\/\/workmimarlik.com\/tr\/portfolio\/akko\/\"><img width=\"606\" height=\"455\" class=\"aux-attachment aux-featured-image attachment-606.66666666667x455 aux-attachment-id-622 \" alt=\"akko-4\" data-ratio=\"1.33\" data-original-w=\"607\" sizes=\"auto\" data-srcset=\"https:\/\/workmimarlik.com\/wp-content\/uploads\/2022\/09\/akko-4-150x113.jpg 150w,https:\/\/workmimarlik.com\/wp-content\/uploads\/2022\/09\/akko-4-300x225.jpg 300w,https:\/\/workmimarlik.com\/wp-content\/uploads\/2022\/09\/akko-4-607x455.jpg 607w,https:\/\/workmimarlik.com\/wp-content\/uploads\/2022\/09\/akko-4-597x447.jpg 597w\" data-src=\"https:\/\/workmimarlik.com\/wp-content\/uploads\/2022\/09\/akko-4-607x455.jpg\" \/><\/a><\/div>                                <\/div>\n\n                                <div class=\"aux-overlay-content\">\n                                                                        <div class=\"aux-portfolio-overlay-buttons\">\n                                        <div class=\"aux-hover-circle-plus aux-delay-2x\">\n                                            <a href=\"https:\/\/workmimarlik.com\/wp-content\/uploads\/2022\/09\/akko-4.jpg\" data-elementor-open-lightbox = \"no\" data-original-width = \"607\" data-original-height = \"455\" data-caption = \"akko-4\" class=\"aux-lightbox-btn \" >\n                                                <div class=\"aux-arrow-nav aux-round aux-hover-slide aux-outline aux-semi-small aux-white\">\n                                                    <span class=\"aux-overlay\"><\/span>\n                                                    <span class=\"aux-svg-arrow aux-medium-plus aux-white\"><\/span>\n                                                    <span class=\"aux-hover-arrow aux-svg-arrow aux-medium-plus aux-black\"><\/span>\n                                                <\/div>\n                                            <\/a>\n                                        <\/div>\n                                        <div class=\"aux-arrow-post-link aux-hover-circle-link\">\n                                            <a href=\"https:\/\/workmimarlik.com\/tr\/portfolio\/akko\/\">\n                                                <div class=\"aux-arrow-nav aux-round aux-hover-slide aux-outline aux-semi-small aux-white\">\n                                                    <span class=\"aux-overlay\"><\/span>\n                                                    <span class=\"aux-svg-arrow aux-medium-right aux-white\"><\/span>\n                                                    <span class=\"aux-hover-arrow aux-svg-arrow aux-medium-right aux-black\"><\/span>\n                                                <\/div>\n                                            <\/a>\n                                        <\/div>\n\n                                    <\/div>\n                                                                                                            <div class=\"entry-main\">\n\n                                                                        <header class=\"entry-header\">\n                                        <h3 class=\"entry-title aux-hover-move-up\">\n                                            <a href=\"https:\/\/workmimarlik.com\/tr\/portfolio\/akko\/\">\n                                                AKKO                                            <\/a>\n                                        <\/h3>\n                                    <\/header>\n                                                                                                            <div class=\"entry-info aux-hover-move-up aux-delay-1x\">\n                                        <span class=\"entry-tax\">\n                                                                                        <a href=\"https:\/\/workmimarlik.com\/tr\/portfolio-cat\/ahsap-fuar-standi\/\" title=\"View all posts in Ah\u015fap Fuar Stand\u0131\" rel=\"category\" >Ah\u015fap Fuar Stand\u0131<\/a>                                        <\/span>\n                                    <\/div>\n                                                                                                            <\/div>\n                                                                <\/div>\n                        <\/article>\n<\/div><div class=\"aux-iso-item aux-loading aux-col\">                         <article class=\"aux-item-overlay aux-hover-active aux-hover-twoway  post-626 portfolio type-portfolio status-publish has-post-thumbnail hentry portfolio-cat-ahsap-fuar-standi portfolio-tag-uncategorized portfolio-filter-uncategorized\" >\n                                <div class=\"entry-media aux-frame-boxed-darken aux-frame-zoom \">\n                                    <div class=\"aux-media-frame aux-media-image\"><a href=\"https:\/\/workmimarlik.com\/tr\/portfolio\/arerko\/\"><img loading=\"lazy\" width=\"606\" height=\"455\" class=\"aux-attachment aux-featured-image attachment-606.66666666667x455 aux-attachment-id-628 \" alt=\"arerko-1\" data-ratio=\"1.33\" data-original-w=\"607\" sizes=\"auto\" data-srcset=\"https:\/\/workmimarlik.com\/wp-content\/uploads\/2022\/09\/arerko-1-150x113.jpg 150w,https:\/\/workmimarlik.com\/wp-content\/uploads\/2022\/09\/arerko-1-300x225.jpg 300w,https:\/\/workmimarlik.com\/wp-content\/uploads\/2022\/09\/arerko-1-607x455.jpg 607w,https:\/\/workmimarlik.com\/wp-content\/uploads\/2022\/09\/arerko-1-597x447.jpg 597w\" data-src=\"https:\/\/workmimarlik.com\/wp-content\/uploads\/2022\/09\/arerko-1-607x455.jpg\" \/><\/a><\/div>                                <\/div>\n\n                                <div class=\"aux-overlay-content\">\n                                                                        <div class=\"aux-portfolio-overlay-buttons\">\n                                        <div class=\"aux-hover-circle-plus aux-delay-2x\">\n                                            <a href=\"https:\/\/workmimarlik.com\/wp-content\/uploads\/2022\/09\/arerko-1.jpg\" data-elementor-open-lightbox = \"no\" data-original-width = \"607\" data-original-height = \"455\" data-caption = \"arerko-1\" class=\"aux-lightbox-btn \" >\n                                                <div class=\"aux-arrow-nav aux-round aux-hover-slide aux-outline aux-semi-small aux-white\">\n                                                    <span class=\"aux-overlay\"><\/span>\n                                                    <span class=\"aux-svg-arrow aux-medium-plus aux-white\"><\/span>\n                                                    <span class=\"aux-hover-arrow aux-svg-arrow aux-medium-plus aux-black\"><\/span>\n                                                <\/div>\n                                            <\/a>\n                                        <\/div>\n                                        <div class=\"aux-arrow-post-link aux-hover-circle-link\">\n                                            <a href=\"https:\/\/workmimarlik.com\/tr\/portfolio\/arerko\/\">\n                                                <div class=\"aux-arrow-nav aux-round aux-hover-slide aux-outline aux-semi-small aux-white\">\n                                                    <span class=\"aux-overlay\"><\/span>\n                                                    <span class=\"aux-svg-arrow aux-medium-right aux-white\"><\/span>\n                                                    <span class=\"aux-hover-arrow aux-svg-arrow aux-medium-right aux-black\"><\/span>\n                                                <\/div>\n                                            <\/a>\n                                        <\/div>\n\n                                    <\/div>\n                                                                                                            <div class=\"entry-main\">\n\n                                                                        <header class=\"entry-header\">\n                                        <h3 class=\"entry-title aux-hover-move-up\">\n                                            <a href=\"https:\/\/workmimarlik.com\/tr\/portfolio\/arerko\/\">\n                                                ARERKO                                            <\/a>\n                                        <\/h3>\n                                    <\/header>\n                                                                                                            <div class=\"entry-info aux-hover-move-up aux-delay-1x\">\n                                        <span class=\"entry-tax\">\n                                                                                        <a href=\"https:\/\/workmimarlik.com\/tr\/portfolio-cat\/ahsap-fuar-standi\/\" title=\"View all posts in Ah\u015fap Fuar Stand\u0131\" rel=\"category\" >Ah\u015fap Fuar Stand\u0131<\/a>                                        <\/span>\n                                    <\/div>\n                                                                                                            <\/div>\n                                                                <\/div>\n                        <\/article>\n<\/div><div class=\"aux-iso-item aux-loading aux-col\">                         <article class=\"aux-item-overlay aux-hover-active aux-hover-twoway  post-634 portfolio type-portfolio status-publish has-post-thumbnail hentry portfolio-cat-ahsap-fuar-standi portfolio-tag-uncategorized portfolio-filter-uncategorized\" >\n                                <div class=\"entry-media aux-frame-boxed-darken aux-frame-zoom \">\n                                    <div class=\"aux-media-frame aux-media-image\"><a href=\"https:\/\/workmimarlik.com\/tr\/portfolio\/ersoy-pano\/\"><img loading=\"lazy\" width=\"606\" height=\"455\" class=\"aux-attachment aux-featured-image attachment-606.66666666667x455 aux-attachment-id-635 \" alt=\"ersoy\" data-ratio=\"1.33\" data-original-w=\"607\" sizes=\"auto\" data-srcset=\"https:\/\/workmimarlik.com\/wp-content\/uploads\/2022\/09\/ersoy-150x113.jpg 150w,https:\/\/workmimarlik.com\/wp-content\/uploads\/2022\/09\/ersoy-300x225.jpg 300w,https:\/\/workmimarlik.com\/wp-content\/uploads\/2022\/09\/ersoy-607x455.jpg 607w,https:\/\/workmimarlik.com\/wp-content\/uploads\/2022\/09\/ersoy-597x447.jpg 597w\" data-src=\"https:\/\/workmimarlik.com\/wp-content\/uploads\/2022\/09\/ersoy-607x455.jpg\" \/><\/a><\/div>                                <\/div>\n\n                                <div class=\"aux-overlay-content\">\n                                                                        <div class=\"aux-portfolio-overlay-buttons\">\n                                        <div class=\"aux-hover-circle-plus aux-delay-2x\">\n                                            <a href=\"https:\/\/workmimarlik.com\/wp-content\/uploads\/2022\/09\/ersoy.jpg\" data-elementor-open-lightbox = \"no\" data-original-width = \"607\" data-original-height = \"455\" data-caption = \"ersoy\" class=\"aux-lightbox-btn \" >\n                                                <div class=\"aux-arrow-nav aux-round aux-hover-slide aux-outline aux-semi-small aux-white\">\n                                                    <span class=\"aux-overlay\"><\/span>\n                                                    <span class=\"aux-svg-arrow aux-medium-plus aux-white\"><\/span>\n                                                    <span class=\"aux-hover-arrow aux-svg-arrow aux-medium-plus aux-black\"><\/span>\n                                                <\/div>\n                                            <\/a>\n                                        <\/div>\n                                        <div class=\"aux-arrow-post-link aux-hover-circle-link\">\n                                            <a href=\"https:\/\/workmimarlik.com\/tr\/portfolio\/ersoy-pano\/\">\n                                                <div class=\"aux-arrow-nav aux-round aux-hover-slide aux-outline aux-semi-small aux-white\">\n                                                    <span class=\"aux-overlay\"><\/span>\n                                                    <span class=\"aux-svg-arrow aux-medium-right aux-white\"><\/span>\n                                                    <span class=\"aux-hover-arrow aux-svg-arrow aux-medium-right aux-black\"><\/span>\n                                                <\/div>\n                                            <\/a>\n                                        <\/div>\n\n                                    <\/div>\n                                                                                                            <div class=\"entry-main\">\n\n                                                                        <header class=\"entry-header\">\n                                        <h3 class=\"entry-title aux-hover-move-up\">\n                                            <a href=\"https:\/\/workmimarlik.com\/tr\/portfolio\/ersoy-pano\/\">\n                                                ERSOY PANO                                            <\/a>\n                                        <\/h3>\n                                    <\/header>\n                                                                                                            <div class=\"entry-info aux-hover-move-up aux-delay-1x\">\n                                        <span class=\"entry-tax\">\n                                                                                        <a href=\"https:\/\/workmimarlik.com\/tr\/portfolio-cat\/ahsap-fuar-standi\/\" title=\"View all posts in Ah\u015fap Fuar Stand\u0131\" rel=\"category\" >Ah\u015fap Fuar Stand\u0131<\/a>                                        <\/span>\n                                    <\/div>\n                                                                                                            <\/div>\n                                                                <\/div>\n                        <\/article>\n<\/div><div class=\"aux-iso-item aux-loading aux-col\">                         <article class=\"aux-item-overlay aux-hover-active aux-hover-twoway  post-640 portfolio type-portfolio status-publish has-post-thumbnail hentry portfolio-cat-maxima-fuar-standi portfolio-tag-uncategorized portfolio-filter-uncategorized\" >\n                                <div class=\"entry-media aux-frame-boxed-darken aux-frame-zoom \">\n                                    <div class=\"aux-media-frame aux-media-image\"><a href=\"https:\/\/workmimarlik.com\/tr\/portfolio\/hakan-otomotiv\/\"><img loading=\"lazy\" width=\"606\" height=\"455\" class=\"aux-attachment aux-featured-image attachment-606.66666666667x455 aux-attachment-id-641 \" alt=\"hakanotomotiv\" data-ratio=\"1.33\" data-original-w=\"607\" sizes=\"auto\" data-srcset=\"https:\/\/workmimarlik.com\/wp-content\/uploads\/2022\/09\/hakanotomotiv-150x113.jpg 150w,https:\/\/workmimarlik.com\/wp-content\/uploads\/2022\/09\/hakanotomotiv-300x225.jpg 300w,https:\/\/workmimarlik.com\/wp-content\/uploads\/2022\/09\/hakanotomotiv-607x455.jpg 607w,https:\/\/workmimarlik.com\/wp-content\/uploads\/2022\/09\/hakanotomotiv-597x447.jpg 597w\" data-src=\"https:\/\/workmimarlik.com\/wp-content\/uploads\/2022\/09\/hakanotomotiv-607x455.jpg\" \/><\/a><\/div>                                <\/div>\n\n                                <div class=\"aux-overlay-content\">\n                                                                        <div class=\"aux-portfolio-overlay-buttons\">\n                                        <div class=\"aux-hover-circle-plus aux-delay-2x\">\n                                            <a href=\"https:\/\/workmimarlik.com\/wp-content\/uploads\/2022\/09\/hakanotomotiv.jpg\" data-elementor-open-lightbox = \"no\" data-original-width = \"607\" data-original-height = \"455\" data-caption = \"hakanotomotiv\" class=\"aux-lightbox-btn \" >\n                                                <div class=\"aux-arrow-nav aux-round aux-hover-slide aux-outline aux-semi-small aux-white\">\n                                                    <span class=\"aux-overlay\"><\/span>\n                                                    <span class=\"aux-svg-arrow aux-medium-plus aux-white\"><\/span>\n                                                    <span class=\"aux-hover-arrow aux-svg-arrow aux-medium-plus aux-black\"><\/span>\n                                                <\/div>\n                                            <\/a>\n                                        <\/div>\n                                        <div class=\"aux-arrow-post-link aux-hover-circle-link\">\n                                            <a href=\"https:\/\/workmimarlik.com\/tr\/portfolio\/hakan-otomotiv\/\">\n                                                <div class=\"aux-arrow-nav aux-round aux-hover-slide aux-outline aux-semi-small aux-white\">\n                                                    <span class=\"aux-overlay\"><\/span>\n                                                    <span class=\"aux-svg-arrow aux-medium-right aux-white\"><\/span>\n                                                    <span class=\"aux-hover-arrow aux-svg-arrow aux-medium-right aux-black\"><\/span>\n                                                <\/div>\n                                            <\/a>\n                                        <\/div>\n\n                                    <\/div>\n                                                                                                            <div class=\"entry-main\">\n\n                                                                        <header class=\"entry-header\">\n                                        <h3 class=\"entry-title aux-hover-move-up\">\n                                            <a href=\"https:\/\/workmimarlik.com\/tr\/portfolio\/hakan-otomotiv\/\">\n                                                HAKAN OTOMOT\u0130V                                            <\/a>\n                                        <\/h3>\n                                    <\/header>\n                                                                                                            <div class=\"entry-info aux-hover-move-up aux-delay-1x\">\n                                        <span class=\"entry-tax\">\n                                                                                        <a href=\"https:\/\/workmimarlik.com\/tr\/portfolio-cat\/maxima-fuar-standi\/\" title=\"View all posts in Maxima Fuar Stand\u0131\" rel=\"category\" >Maxima Fuar Stand\u0131<\/a>                                        <\/span>\n                                    <\/div>\n                                                                                                            <\/div>\n                                                                <\/div>\n                        <\/article>\n<\/div><div class=\"aux-iso-item aux-loading aux-col\">                         <article class=\"aux-item-overlay aux-hover-active aux-hover-twoway  post-645 portfolio type-portfolio status-publish has-post-thumbnail hentry portfolio-cat-maxima-fuar-standi portfolio-tag-uncategorized portfolio-filter-uncategorized\" >\n                                <div class=\"entry-media aux-frame-boxed-darken aux-frame-zoom \">\n                                    <div class=\"aux-media-frame aux-media-image\"><a href=\"https:\/\/workmimarlik.com\/tr\/portfolio\/oymak-otomotiv\/\"><img loading=\"lazy\" width=\"606\" height=\"455\" class=\"aux-attachment aux-featured-image attachment-606.66666666667x455 aux-attachment-id-651 \" alt=\"oymak-5\" data-ratio=\"1.33\" data-original-w=\"607\" sizes=\"auto\" data-srcset=\"https:\/\/workmimarlik.com\/wp-content\/uploads\/2022\/09\/oymak-5-150x113.jpg 150w,https:\/\/workmimarlik.com\/wp-content\/uploads\/2022\/09\/oymak-5-300x225.jpg 300w,https:\/\/workmimarlik.com\/wp-content\/uploads\/2022\/09\/oymak-5-607x455.jpg 607w,https:\/\/workmimarlik.com\/wp-content\/uploads\/2022\/09\/oymak-5-597x447.jpg 597w\" data-src=\"https:\/\/workmimarlik.com\/wp-content\/uploads\/2022\/09\/oymak-5-607x455.jpg\" \/><\/a><\/div>                                <\/div>\n\n                                <div class=\"aux-overlay-content\">\n                                                                        <div class=\"aux-portfolio-overlay-buttons\">\n                                        <div class=\"aux-hover-circle-plus aux-delay-2x\">\n                                            <a href=\"https:\/\/workmimarlik.com\/wp-content\/uploads\/2022\/09\/oymak-5.jpg\" data-elementor-open-lightbox = \"no\" data-original-width = \"607\" data-original-height = \"455\" data-caption = \"oymak-5\" class=\"aux-lightbox-btn \" >\n                                                <div class=\"aux-arrow-nav aux-round aux-hover-slide aux-outline aux-semi-small aux-white\">\n                                                    <span class=\"aux-overlay\"><\/span>\n                                                    <span class=\"aux-svg-arrow aux-medium-plus aux-white\"><\/span>\n                                                    <span class=\"aux-hover-arrow aux-svg-arrow aux-medium-plus aux-black\"><\/span>\n                                                <\/div>\n                                            <\/a>\n                                        <\/div>\n                                        <div class=\"aux-arrow-post-link aux-hover-circle-link\">\n                                            <a href=\"https:\/\/workmimarlik.com\/tr\/portfolio\/oymak-otomotiv\/\">\n                                                <div class=\"aux-arrow-nav aux-round aux-hover-slide aux-outline aux-semi-small aux-white\">\n                                                    <span class=\"aux-overlay\"><\/span>\n                                                    <span class=\"aux-svg-arrow aux-medium-right aux-white\"><\/span>\n                                                    <span class=\"aux-hover-arrow aux-svg-arrow aux-medium-right aux-black\"><\/span>\n                                                <\/div>\n                                            <\/a>\n                                        <\/div>\n\n                                    <\/div>\n                                                                                                            <div class=\"entry-main\">\n\n                                                                        <header class=\"entry-header\">\n                                        <h3 class=\"entry-title aux-hover-move-up\">\n                                            <a href=\"https:\/\/workmimarlik.com\/tr\/portfolio\/oymak-otomotiv\/\">\n                                                OYMAK OTOMOT\u0130V                                            <\/a>\n                                        <\/h3>\n                                    <\/header>\n                                                                                                            <div class=\"entry-info aux-hover-move-up aux-delay-1x\">\n                                        <span class=\"entry-tax\">\n                                                                                        <a href=\"https:\/\/workmimarlik.com\/tr\/portfolio-cat\/maxima-fuar-standi\/\" title=\"View all posts in Maxima Fuar Stand\u0131\" rel=\"category\" >Maxima Fuar Stand\u0131<\/a>                                        <\/span>\n                                    <\/div>\n                                                                                                            <\/div>\n                                                                <\/div>\n                        <\/article>\n<\/div><div class=\"aux-iso-item aux-loading aux-col\">                         <article class=\"aux-item-overlay aux-hover-active aux-hover-twoway  post-655 portfolio type-portfolio status-publish has-post-thumbnail hentry portfolio-cat-ahsap-fuar-standi portfolio-tag-uncategorized portfolio-filter-uncategorized\" >\n                                <div class=\"entry-media aux-frame-boxed-darken aux-frame-zoom \">\n                                    <div class=\"aux-media-frame aux-media-image\"><a href=\"https:\/\/workmimarlik.com\/tr\/portfolio\/sulzer\/\"><img loading=\"lazy\" width=\"606\" height=\"455\" class=\"aux-attachment aux-featured-image attachment-606.66666666667x455 aux-attachment-id-656 \" alt=\"sulzer\" data-ratio=\"1.33\" data-original-w=\"607\" sizes=\"auto\" data-srcset=\"https:\/\/workmimarlik.com\/wp-content\/uploads\/2022\/09\/sulzer-150x113.jpg 150w,https:\/\/workmimarlik.com\/wp-content\/uploads\/2022\/09\/sulzer-300x225.jpg 300w,https:\/\/workmimarlik.com\/wp-content\/uploads\/2022\/09\/sulzer-607x455.jpg 607w,https:\/\/workmimarlik.com\/wp-content\/uploads\/2022\/09\/sulzer-597x447.jpg 597w\" data-src=\"https:\/\/workmimarlik.com\/wp-content\/uploads\/2022\/09\/sulzer-607x455.jpg\" \/><\/a><\/div>                                <\/div>\n\n                                <div class=\"aux-overlay-content\">\n                                                                        <div class=\"aux-portfolio-overlay-buttons\">\n                                        <div class=\"aux-hover-circle-plus aux-delay-2x\">\n                                            <a href=\"https:\/\/workmimarlik.com\/wp-content\/uploads\/2022\/09\/sulzer.jpg\" data-elementor-open-lightbox = \"no\" data-original-width = \"607\" data-original-height = \"455\" data-caption = \"sulzer\" class=\"aux-lightbox-btn \" >\n                                                <div class=\"aux-arrow-nav aux-round aux-hover-slide aux-outline aux-semi-small aux-white\">\n                                                    <span class=\"aux-overlay\"><\/span>\n                                                    <span class=\"aux-svg-arrow aux-medium-plus aux-white\"><\/span>\n                                                    <span class=\"aux-hover-arrow aux-svg-arrow aux-medium-plus aux-black\"><\/span>\n                                                <\/div>\n                                            <\/a>\n                                        <\/div>\n                                        <div class=\"aux-arrow-post-link aux-hover-circle-link\">\n                                            <a href=\"https:\/\/workmimarlik.com\/tr\/portfolio\/sulzer\/\">\n                                                <div class=\"aux-arrow-nav aux-round aux-hover-slide aux-outline aux-semi-small aux-white\">\n                                                    <span class=\"aux-overlay\"><\/span>\n                                                    <span class=\"aux-svg-arrow aux-medium-right aux-white\"><\/span>\n                                                    <span class=\"aux-hover-arrow aux-svg-arrow aux-medium-right aux-black\"><\/span>\n                                                <\/div>\n                                            <\/a>\n                                        <\/div>\n\n                                    <\/div>\n                                                                                                            <div class=\"entry-main\">\n\n                                                                        <header class=\"entry-header\">\n                                        <h3 class=\"entry-title aux-hover-move-up\">\n                                            <a href=\"https:\/\/workmimarlik.com\/tr\/portfolio\/sulzer\/\">\n                                                SULZER                                            <\/a>\n                                        <\/h3>\n                                    <\/header>\n                                                                                                            <div class=\"entry-info aux-hover-move-up aux-delay-1x\">\n                                        <span class=\"entry-tax\">\n                                                                                        <a href=\"https:\/\/workmimarlik.com\/tr\/portfolio-cat\/ahsap-fuar-standi\/\" title=\"View all posts in Ah\u015fap Fuar Stand\u0131\" rel=\"category\" >Ah\u015fap Fuar Stand\u0131<\/a>                                        <\/span>\n                                    <\/div>\n                                                                                                            <\/div>\n                                                                <\/div>\n                        <\/article>\n<\/div><div class=\"aux-iso-item aux-loading aux-col\">                         <article class=\"aux-item-overlay aux-hover-active aux-hover-twoway  post-660 portfolio type-portfolio status-publish has-post-thumbnail hentry portfolio-cat-ahsap-fuar-standi portfolio-tag-uncategorized portfolio-filter-uncategorized\" >\n                                <div class=\"entry-media aux-frame-boxed-darken aux-frame-zoom \">\n                                    <div class=\"aux-media-frame aux-media-image\"><a href=\"https:\/\/workmimarlik.com\/tr\/portfolio\/yilmaz-kimya\/\"><img loading=\"lazy\" width=\"606\" height=\"455\" class=\"aux-attachment aux-featured-image attachment-606.66666666667x455 aux-attachment-id-663 \" alt=\"yilmazkimya-2\" data-ratio=\"1.33\" data-original-w=\"607\" sizes=\"auto\" data-srcset=\"https:\/\/workmimarlik.com\/wp-content\/uploads\/2022\/09\/yilmazkimya-2-150x113.jpg 150w,https:\/\/workmimarlik.com\/wp-content\/uploads\/2022\/09\/yilmazkimya-2-300x225.jpg 300w,https:\/\/workmimarlik.com\/wp-content\/uploads\/2022\/09\/yilmazkimya-2-607x455.jpg 607w,https:\/\/workmimarlik.com\/wp-content\/uploads\/2022\/09\/yilmazkimya-2-597x447.jpg 597w\" data-src=\"https:\/\/workmimarlik.com\/wp-content\/uploads\/2022\/09\/yilmazkimya-2-607x455.jpg\" \/><\/a><\/div>                                <\/div>\n\n                                <div class=\"aux-overlay-content\">\n                                                                        <div class=\"aux-portfolio-overlay-buttons\">\n                                        <div class=\"aux-hover-circle-plus aux-delay-2x\">\n                                            <a href=\"https:\/\/workmimarlik.com\/wp-content\/uploads\/2022\/09\/yilmazkimya-2.jpg\" data-elementor-open-lightbox = \"no\" data-original-width = \"607\" data-original-height = \"455\" data-caption = \"yilmazkimya-2\" class=\"aux-lightbox-btn \" >\n                                                <div class=\"aux-arrow-nav aux-round aux-hover-slide aux-outline aux-semi-small aux-white\">\n                                                    <span class=\"aux-overlay\"><\/span>\n                                                    <span class=\"aux-svg-arrow aux-medium-plus aux-white\"><\/span>\n                                                    <span class=\"aux-hover-arrow aux-svg-arrow aux-medium-plus aux-black\"><\/span>\n                                                <\/div>\n                                            <\/a>\n                                        <\/div>\n                                        <div class=\"aux-arrow-post-link aux-hover-circle-link\">\n                                            <a href=\"https:\/\/workmimarlik.com\/tr\/portfolio\/yilmaz-kimya\/\">\n                                                <div class=\"aux-arrow-nav aux-round aux-hover-slide aux-outline aux-semi-small aux-white\">\n                                                    <span class=\"aux-overlay\"><\/span>\n                                                    <span class=\"aux-svg-arrow aux-medium-right aux-white\"><\/span>\n                                                    <span class=\"aux-hover-arrow aux-svg-arrow aux-medium-right aux-black\"><\/span>\n                                                <\/div>\n                                            <\/a>\n                                        <\/div>\n\n                                    <\/div>\n                                                                                                            <div class=\"entry-main\">\n\n                                                                        <header class=\"entry-header\">\n                                        <h3 class=\"entry-title aux-hover-move-up\">\n                                            <a href=\"https:\/\/workmimarlik.com\/tr\/portfolio\/yilmaz-kimya\/\">\n                                                YILMAZ K\u0130MYA                                            <\/a>\n                                        <\/h3>\n                                    <\/header>\n                                                                                                            <div class=\"entry-info aux-hover-move-up aux-delay-1x\">\n                                        <span class=\"entry-tax\">\n                                                                                        <a href=\"https:\/\/workmimarlik.com\/tr\/portfolio-cat\/ahsap-fuar-standi\/\" title=\"View all posts in Ah\u015fap Fuar Stand\u0131\" rel=\"category\" >Ah\u015fap Fuar Stand\u0131<\/a>                                        <\/span>\n                                    <\/div>\n                                                                                                            <\/div>\n                                                                <\/div>\n                        <\/article>\n<\/div><div class=\"aux-iso-item aux-loading aux-col\">                         <article class=\"aux-item-overlay aux-hover-active aux-hover-twoway  post-765 portfolio type-portfolio status-publish has-post-thumbnail hentry portfolio-cat-ahsap-fuar-standi portfolio-tag-uncategorized portfolio-filter-uncategorized\" >\n                                <div class=\"entry-media aux-frame-boxed-darken aux-frame-zoom \">\n                                    <div class=\"aux-media-frame aux-media-image\"><a href=\"https:\/\/workmimarlik.com\/tr\/portfolio\/oymak-otomotiv-2\/\"><img loading=\"lazy\" width=\"606\" height=\"455\" class=\"aux-attachment aux-featured-image attachment-606.66666666667x455 aux-attachment-id-766 \" alt=\"aydinonat\" data-ratio=\"1.33\" data-original-w=\"607\" sizes=\"auto\" data-srcset=\"https:\/\/workmimarlik.com\/wp-content\/uploads\/2022\/09\/aydinonat-150x113.jpg 150w,https:\/\/workmimarlik.com\/wp-content\/uploads\/2022\/09\/aydinonat-300x225.jpg 300w,https:\/\/workmimarlik.com\/wp-content\/uploads\/2022\/09\/aydinonat-607x455.jpg 607w,https:\/\/workmimarlik.com\/wp-content\/uploads\/2022\/09\/aydinonat-597x447.jpg 597w\" data-src=\"https:\/\/workmimarlik.com\/wp-content\/uploads\/2022\/09\/aydinonat-607x455.jpg\" \/><\/a><\/div>                                <\/div>\n\n                                <div class=\"aux-overlay-content\">\n                                                                        <div class=\"aux-portfolio-overlay-buttons\">\n                                        <div class=\"aux-hover-circle-plus aux-delay-2x\">\n                                            <a href=\"https:\/\/workmimarlik.com\/wp-content\/uploads\/2022\/09\/aydinonat.jpg\" data-elementor-open-lightbox = \"no\" data-original-width = \"607\" data-original-height = \"455\" data-caption = \"aydinonat\" class=\"aux-lightbox-btn \" >\n                                                <div class=\"aux-arrow-nav aux-round aux-hover-slide aux-outline aux-semi-small aux-white\">\n                                                    <span class=\"aux-overlay\"><\/span>\n                                                    <span class=\"aux-svg-arrow aux-medium-plus aux-white\"><\/span>\n                                                    <span class=\"aux-hover-arrow aux-svg-arrow aux-medium-plus aux-black\"><\/span>\n                                                <\/div>\n                                            <\/a>\n                                        <\/div>\n                                        <div class=\"aux-arrow-post-link aux-hover-circle-link\">\n                                            <a href=\"https:\/\/workmimarlik.com\/tr\/portfolio\/oymak-otomotiv-2\/\">\n                                                <div class=\"aux-arrow-nav aux-round aux-hover-slide aux-outline aux-semi-small aux-white\">\n                                                    <span class=\"aux-overlay\"><\/span>\n                                                    <span class=\"aux-svg-arrow aux-medium-right aux-white\"><\/span>\n                                                    <span class=\"aux-hover-arrow aux-svg-arrow aux-medium-right aux-black\"><\/span>\n                                                <\/div>\n                                            <\/a>\n                                        <\/div>\n\n                                    <\/div>\n                                                                                                            <div class=\"entry-main\">\n\n                                                                        <header class=\"entry-header\">\n                                        <h3 class=\"entry-title aux-hover-move-up\">\n                                            <a href=\"https:\/\/workmimarlik.com\/tr\/portfolio\/oymak-otomotiv-2\/\">\n                                                AYDIN ONAT                                            <\/a>\n                                        <\/h3>\n                                    <\/header>\n                                                                                                            <div class=\"entry-info aux-hover-move-up aux-delay-1x\">\n                                        <span class=\"entry-tax\">\n                                                                                        <a href=\"https:\/\/workmimarlik.com\/tr\/portfolio-cat\/ahsap-fuar-standi\/\" title=\"View all posts in Ah\u015fap Fuar Stand\u0131\" rel=\"category\" >Ah\u015fap Fuar Stand\u0131<\/a>                                        <\/span>\n                                    <\/div>\n                                                                                                            <\/div>\n                                                                <\/div>\n                        <\/article>\n<\/div><div class=\"aux-iso-item aux-loading aux-col\">                         <article class=\"aux-item-overlay aux-hover-active aux-hover-twoway  post-779 portfolio type-portfolio status-publish has-post-thumbnail hentry portfolio-cat-ahsap-fuar-standi portfolio-tag-uncategorized portfolio-filter-uncategorized\" >\n                                <div class=\"entry-media aux-frame-boxed-darken aux-frame-zoom \">\n                                    <div class=\"aux-media-frame aux-media-image\"><a href=\"https:\/\/workmimarlik.com\/tr\/portfolio\/arerko-2\/\"><img loading=\"lazy\" width=\"606\" height=\"455\" class=\"aux-attachment aux-featured-image attachment-606.66666666667x455 aux-attachment-id-784 \" alt=\"trnormanurunleri-3\" data-ratio=\"1.33\" data-original-w=\"607\" sizes=\"auto\" data-srcset=\"https:\/\/workmimarlik.com\/wp-content\/uploads\/2022\/09\/trnormanurunleri-3-150x113.jpg 150w,https:\/\/workmimarlik.com\/wp-content\/uploads\/2022\/09\/trnormanurunleri-3-300x225.jpg 300w,https:\/\/workmimarlik.com\/wp-content\/uploads\/2022\/09\/trnormanurunleri-3-607x455.jpg 607w,https:\/\/workmimarlik.com\/wp-content\/uploads\/2022\/09\/trnormanurunleri-3-597x447.jpg 597w\" data-src=\"https:\/\/workmimarlik.com\/wp-content\/uploads\/2022\/09\/trnormanurunleri-3-607x455.jpg\" \/><\/a><\/div>                                <\/div>\n\n                                <div class=\"aux-overlay-content\">\n                                                                        <div class=\"aux-portfolio-overlay-buttons\">\n                                        <div class=\"aux-hover-circle-plus aux-delay-2x\">\n                                            <a href=\"https:\/\/workmimarlik.com\/wp-content\/uploads\/2022\/09\/trnormanurunleri-3.jpg\" data-elementor-open-lightbox = \"no\" data-original-width = \"607\" data-original-height = \"455\" data-caption = \"trnormanurunleri-3\" class=\"aux-lightbox-btn \" >\n                                                <div class=\"aux-arrow-nav aux-round aux-hover-slide aux-outline aux-semi-small aux-white\">\n                                                    <span class=\"aux-overlay\"><\/span>\n                                                    <span class=\"aux-svg-arrow aux-medium-plus aux-white\"><\/span>\n                                                    <span class=\"aux-hover-arrow aux-svg-arrow aux-medium-plus aux-black\"><\/span>\n                                                <\/div>\n                                            <\/a>\n                                        <\/div>\n                                        <div class=\"aux-arrow-post-link aux-hover-circle-link\">\n                                            <a href=\"https:\/\/workmimarlik.com\/tr\/portfolio\/arerko-2\/\">\n                                                <div class=\"aux-arrow-nav aux-round aux-hover-slide aux-outline aux-semi-small aux-white\">\n                                                    <span class=\"aux-overlay\"><\/span>\n                                                    <span class=\"aux-svg-arrow aux-medium-right aux-white\"><\/span>\n                                                    <span class=\"aux-hover-arrow aux-svg-arrow aux-medium-right aux-black\"><\/span>\n                                                <\/div>\n                                            <\/a>\n                                        <\/div>\n\n                                    <\/div>\n                                                                                                            <div class=\"entry-main\">\n\n                                                                        <header class=\"entry-header\">\n                                        <h3 class=\"entry-title aux-hover-move-up\">\n                                            <a href=\"https:\/\/workmimarlik.com\/tr\/portfolio\/arerko-2\/\">\n                                                TRN ORMAN \u00dcR\u00dcNLER\u0130                                            <\/a>\n                                        <\/h3>\n                                    <\/header>\n                                                                                                            <div class=\"entry-info aux-hover-move-up aux-delay-1x\">\n                                        <span class=\"entry-tax\">\n                                                                                        <a href=\"https:\/\/workmimarlik.com\/tr\/portfolio-cat\/ahsap-fuar-standi\/\" title=\"View all posts in Ah\u015fap Fuar Stand\u0131\" rel=\"category\" >Ah\u015fap Fuar Stand\u0131<\/a>                                        <\/span>\n                                    <\/div>\n                                                                                                            <\/div>\n                                                                <\/div>\n                        <\/article>\n<\/div><div class=\"aux-iso-item aux-loading aux-col\">                         <article class=\"aux-item-overlay aux-hover-active aux-hover-twoway  post-789 portfolio type-portfolio status-publish has-post-thumbnail hentry portfolio-cat-maxima-fuar-standi portfolio-tag-uncategorized portfolio-filter-uncategorized\" >\n                                <div class=\"entry-media aux-frame-boxed-darken aux-frame-zoom \">\n                                    <div class=\"aux-media-frame aux-media-image\"><a href=\"https:\/\/workmimarlik.com\/tr\/portfolio\/hakan-otomotiv-2\/\"><img loading=\"lazy\" width=\"606\" height=\"455\" class=\"aux-attachment aux-featured-image attachment-606.66666666667x455 aux-attachment-id-792 \" alt=\"petronankimya-2\" data-ratio=\"1.33\" data-original-w=\"607\" sizes=\"auto\" data-srcset=\"https:\/\/workmimarlik.com\/wp-content\/uploads\/2022\/09\/petronankimya-2-150x113.jpg 150w,https:\/\/workmimarlik.com\/wp-content\/uploads\/2022\/09\/petronankimya-2-300x225.jpg 300w,https:\/\/workmimarlik.com\/wp-content\/uploads\/2022\/09\/petronankimya-2-607x455.jpg 607w,https:\/\/workmimarlik.com\/wp-content\/uploads\/2022\/09\/petronankimya-2-597x447.jpg 597w\" data-src=\"https:\/\/workmimarlik.com\/wp-content\/uploads\/2022\/09\/petronankimya-2-607x455.jpg\" \/><\/a><\/div>                                <\/div>\n\n                                <div class=\"aux-overlay-content\">\n                                                                        <div class=\"aux-portfolio-overlay-buttons\">\n                                        <div class=\"aux-hover-circle-plus aux-delay-2x\">\n                                            <a href=\"https:\/\/workmimarlik.com\/wp-content\/uploads\/2022\/09\/petronankimya-2.jpg\" data-elementor-open-lightbox = \"no\" data-original-width = \"607\" data-original-height = \"455\" data-caption = \"petronankimya-2\" class=\"aux-lightbox-btn \" >\n                                                <div class=\"aux-arrow-nav aux-round aux-hover-slide aux-outline aux-semi-small aux-white\">\n                                                    <span class=\"aux-overlay\"><\/span>\n                                                    <span class=\"aux-svg-arrow aux-medium-plus aux-white\"><\/span>\n                                                    <span class=\"aux-hover-arrow aux-svg-arrow aux-medium-plus aux-black\"><\/span>\n                                                <\/div>\n                                            <\/a>\n                                        <\/div>\n                                        <div class=\"aux-arrow-post-link aux-hover-circle-link\">\n                                            <a href=\"https:\/\/workmimarlik.com\/tr\/portfolio\/hakan-otomotiv-2\/\">\n                                                <div class=\"aux-arrow-nav aux-round aux-hover-slide aux-outline aux-semi-small aux-white\">\n                                                    <span class=\"aux-overlay\"><\/span>\n                                                    <span class=\"aux-svg-arrow aux-medium-right aux-white\"><\/span>\n                                                    <span class=\"aux-hover-arrow aux-svg-arrow aux-medium-right aux-black\"><\/span>\n                                                <\/div>\n                                            <\/a>\n                                        <\/div>\n\n                                    <\/div>\n                                                                                                            <div class=\"entry-main\">\n\n                                                                        <header class=\"entry-header\">\n                                        <h3 class=\"entry-title aux-hover-move-up\">\n                                            <a href=\"https:\/\/workmimarlik.com\/tr\/portfolio\/hakan-otomotiv-2\/\">\n                                                PETRONAN K\u0130MYA                                            <\/a>\n                                        <\/h3>\n                                    <\/header>\n                                                                                                            <div class=\"entry-info aux-hover-move-up aux-delay-1x\">\n                                        <span class=\"entry-tax\">\n                                                                                        <a href=\"https:\/\/workmimarlik.com\/tr\/portfolio-cat\/maxima-fuar-standi\/\" title=\"View all posts in Maxima Fuar Stand\u0131\" rel=\"category\" >Maxima Fuar Stand\u0131<\/a>                                        <\/span>\n                                    <\/div>\n                                                                                                            <\/div>\n                                                                <\/div>\n                        <\/article>\n<\/div><div class=\"aux-iso-item aux-loading aux-col\">                         <article class=\"aux-item-overlay aux-hover-active aux-hover-twoway  post-886 portfolio type-portfolio status-publish has-post-thumbnail hentry portfolio-cat-maxima-fuar-standi portfolio-tag-uncategorized portfolio-filter-uncategorized\" >\n                                <div class=\"entry-media aux-frame-boxed-darken aux-frame-zoom \">\n                                    <div class=\"aux-media-frame aux-media-image\"><a href=\"https:\/\/workmimarlik.com\/tr\/portfolio\/cinarli-makine\/\"><img loading=\"lazy\" width=\"606\" height=\"455\" class=\"aux-attachment aux-featured-image attachment-606.66666666667x455 aux-attachment-id-887 \" alt=\"photo_2022-11-17_12-37-38 (2)\" data-ratio=\"1.33\" data-original-w=\"1280\" sizes=\"auto\" data-srcset=\"https:\/\/workmimarlik.com\/wp-content\/uploads\/2022\/12\/photo_2022-11-17_12-37-38-2-150x113.jpg 150w,https:\/\/workmimarlik.com\/wp-content\/uploads\/2022\/12\/photo_2022-11-17_12-37-38-2-300x225.jpg 300w,https:\/\/workmimarlik.com\/wp-content\/uploads\/2022\/12\/photo_2022-11-17_12-37-38-2-768x576.jpg 768w,https:\/\/workmimarlik.com\/wp-content\/uploads\/2022\/12\/photo_2022-11-17_12-37-38-2-1024x768.jpg 1024w,https:\/\/workmimarlik.com\/wp-content\/uploads\/2022\/12\/photo_2022-11-17_12-37-38-2-607x455.jpg 607w,https:\/\/workmimarlik.com\/wp-content\/uploads\/2022\/12\/photo_2022-11-17_12-37-38-2-1270x952.jpg 1270w\" data-src=\"https:\/\/workmimarlik.com\/wp-content\/uploads\/2022\/12\/photo_2022-11-17_12-37-38-2-607x455.jpg\" \/><\/a><\/div>                                <\/div>\n\n                                <div class=\"aux-overlay-content\">\n                                                                        <div class=\"aux-portfolio-overlay-buttons\">\n                                        <div class=\"aux-hover-circle-plus aux-delay-2x\">\n                                            <a href=\"https:\/\/workmimarlik.com\/wp-content\/uploads\/2022\/12\/photo_2022-11-17_12-37-38-2.jpg\" data-elementor-open-lightbox = \"no\" data-original-width = \"1280\" data-original-height = \"962\" data-caption = \"photo_2022-11-17_12-37-38 (2)\" class=\"aux-lightbox-btn \" >\n                                                <div class=\"aux-arrow-nav aux-round aux-hover-slide aux-outline aux-semi-small aux-white\">\n                                                    <span class=\"aux-overlay\"><\/span>\n                                                    <span class=\"aux-svg-arrow aux-medium-plus aux-white\"><\/span>\n                                                    <span class=\"aux-hover-arrow aux-svg-arrow aux-medium-plus aux-black\"><\/span>\n                                                <\/div>\n                                            <\/a>\n                                        <\/div>\n                                        <div class=\"aux-arrow-post-link aux-hover-circle-link\">\n                                            <a href=\"https:\/\/workmimarlik.com\/tr\/portfolio\/cinarli-makine\/\">\n                                                <div class=\"aux-arrow-nav aux-round aux-hover-slide aux-outline aux-semi-small aux-white\">\n                                                    <span class=\"aux-overlay\"><\/span>\n                                                    <span class=\"aux-svg-arrow aux-medium-right aux-white\"><\/span>\n                                                    <span class=\"aux-hover-arrow aux-svg-arrow aux-medium-right aux-black\"><\/span>\n                                                <\/div>\n                                            <\/a>\n                                        <\/div>\n\n                                    <\/div>\n                                                                                                            <div class=\"entry-main\">\n\n                                                                        <header class=\"entry-header\">\n                                        <h3 class=\"entry-title aux-hover-move-up\">\n                                            <a href=\"https:\/\/workmimarlik.com\/tr\/portfolio\/cinarli-makine\/\">\n                                                \u00c7INARLI MAK\u0130NE                                            <\/a>\n                                        <\/h3>\n                                    <\/header>\n                                                                                                            <div class=\"entry-info aux-hover-move-up aux-delay-1x\">\n                                        <span class=\"entry-tax\">\n                                                                                        <a href=\"https:\/\/workmimarlik.com\/tr\/portfolio-cat\/maxima-fuar-standi\/\" title=\"View all posts in Maxima Fuar Stand\u0131\" rel=\"category\" >Maxima Fuar Stand\u0131<\/a>                                        <\/span>\n                                    <\/div>\n                                                                                                            <\/div>\n                                                                <\/div>\n                        <\/article>\n<\/div><div class=\"aux-iso-item aux-loading aux-col\">                         <article class=\"aux-item-overlay aux-hover-active aux-hover-twoway  post-895 portfolio type-portfolio status-publish has-post-thumbnail hentry portfolio-cat-ahsap-fuar-standi portfolio-tag-uncategorized portfolio-filter-uncategorized\" >\n                                <div class=\"entry-media aux-frame-boxed-darken aux-frame-zoom \">\n                                    <div class=\"aux-media-frame aux-media-image\"><a href=\"https:\/\/workmimarlik.com\/tr\/portfolio\/damra-ambalaj\/\"><img loading=\"lazy\" width=\"606\" height=\"455\" class=\"aux-attachment aux-featured-image attachment-606.66666666667x455 aux-attachment-id-896 \" alt=\"photo_2022-11-17_12-40-25\" data-ratio=\"1.33\" data-original-w=\"1280\" sizes=\"auto\" data-srcset=\"https:\/\/workmimarlik.com\/wp-content\/uploads\/2022\/12\/photo_2022-11-17_12-40-25-150x113.jpg 150w,https:\/\/workmimarlik.com\/wp-content\/uploads\/2022\/12\/photo_2022-11-17_12-40-25-300x225.jpg 300w,https:\/\/workmimarlik.com\/wp-content\/uploads\/2022\/12\/photo_2022-11-17_12-40-25-768x576.jpg 768w,https:\/\/workmimarlik.com\/wp-content\/uploads\/2022\/12\/photo_2022-11-17_12-40-25-1024x768.jpg 1024w,https:\/\/workmimarlik.com\/wp-content\/uploads\/2022\/12\/photo_2022-11-17_12-40-25-607x455.jpg 607w,https:\/\/workmimarlik.com\/wp-content\/uploads\/2022\/12\/photo_2022-11-17_12-40-25-1270x952.jpg 1270w\" data-src=\"https:\/\/workmimarlik.com\/wp-content\/uploads\/2022\/12\/photo_2022-11-17_12-40-25-607x455.jpg\" \/><\/a><\/div>                                <\/div>\n\n                                <div class=\"aux-overlay-content\">\n                                                                        <div class=\"aux-portfolio-overlay-buttons\">\n                                        <div class=\"aux-hover-circle-plus aux-delay-2x\">\n                                            <a href=\"https:\/\/workmimarlik.com\/wp-content\/uploads\/2022\/12\/photo_2022-11-17_12-40-25.jpg\" data-elementor-open-lightbox = \"no\" data-original-width = \"1280\" data-original-height = \"960\" data-caption = \"photo_2022-11-17_12-40-25\" class=\"aux-lightbox-btn \" >\n                                                <div class=\"aux-arrow-nav aux-round aux-hover-slide aux-outline aux-semi-small aux-white\">\n                                                    <span class=\"aux-overlay\"><\/span>\n                                                    <span class=\"aux-svg-arrow aux-medium-plus aux-white\"><\/span>\n                                                    <span class=\"aux-hover-arrow aux-svg-arrow aux-medium-plus aux-black\"><\/span>\n                                                <\/div>\n                                            <\/a>\n                                        <\/div>\n                                        <div class=\"aux-arrow-post-link aux-hover-circle-link\">\n                                            <a href=\"https:\/\/workmimarlik.com\/tr\/portfolio\/damra-ambalaj\/\">\n                                                <div class=\"aux-arrow-nav aux-round aux-hover-slide aux-outline aux-semi-small aux-white\">\n                                                    <span class=\"aux-overlay\"><\/span>\n                                                    <span class=\"aux-svg-arrow aux-medium-right aux-white\"><\/span>\n                                                    <span class=\"aux-hover-arrow aux-svg-arrow aux-medium-right aux-black\"><\/span>\n                                                <\/div>\n                                            <\/a>\n                                        <\/div>\n\n                                    <\/div>\n                                                                                                            <div class=\"entry-main\">\n\n                                                                        <header class=\"entry-header\">\n                                        <h3 class=\"entry-title aux-hover-move-up\">\n                                            <a href=\"https:\/\/workmimarlik.com\/tr\/portfolio\/damra-ambalaj\/\">\n                                                DAMRA AMBALAJ                                            <\/a>\n                                        <\/h3>\n                                    <\/header>\n                                                                                                            <div class=\"entry-info aux-hover-move-up aux-delay-1x\">\n                                        <span class=\"entry-tax\">\n                                                                                        <a href=\"https:\/\/workmimarlik.com\/tr\/portfolio-cat\/ahsap-fuar-standi\/\" title=\"View all posts in Ah\u015fap Fuar Stand\u0131\" rel=\"category\" >Ah\u015fap Fuar Stand\u0131<\/a>                                        <\/span>\n                                    <\/div>\n                                                                                                            <\/div>\n                                                                <\/div>\n                        <\/article>\n<\/div><div class=\"aux-iso-item aux-loading aux-col\">                         <article class=\"aux-item-overlay aux-hover-active aux-hover-twoway  post-905 portfolio type-portfolio status-publish has-post-thumbnail hentry portfolio-cat-maxima-fuar-standi portfolio-tag-uncategorized portfolio-filter-uncategorized\" >\n                                <div class=\"entry-media aux-frame-boxed-darken aux-frame-zoom \">\n                                    <div class=\"aux-media-frame aux-media-image\"><a href=\"https:\/\/workmimarlik.com\/tr\/portfolio\/dekoplas-plastik\/\"><img loading=\"lazy\" width=\"606\" height=\"455\" class=\"aux-attachment aux-featured-image attachment-606.66666666667x455 aux-attachment-id-906 \" alt=\"photo_2022-11-17_12-42-20\" data-ratio=\"1.33\" data-original-w=\"1280\" sizes=\"auto\" data-srcset=\"https:\/\/workmimarlik.com\/wp-content\/uploads\/2022\/12\/photo_2022-11-17_12-42-20-150x113.jpg 150w,https:\/\/workmimarlik.com\/wp-content\/uploads\/2022\/12\/photo_2022-11-17_12-42-20-300x225.jpg 300w,https:\/\/workmimarlik.com\/wp-content\/uploads\/2022\/12\/photo_2022-11-17_12-42-20-768x576.jpg 768w,https:\/\/workmimarlik.com\/wp-content\/uploads\/2022\/12\/photo_2022-11-17_12-42-20-1024x768.jpg 1024w,https:\/\/workmimarlik.com\/wp-content\/uploads\/2022\/12\/photo_2022-11-17_12-42-20-607x455.jpg 607w,https:\/\/workmimarlik.com\/wp-content\/uploads\/2022\/12\/photo_2022-11-17_12-42-20-1270x952.jpg 1270w\" data-src=\"https:\/\/workmimarlik.com\/wp-content\/uploads\/2022\/12\/photo_2022-11-17_12-42-20-607x455.jpg\" \/><\/a><\/div>                                <\/div>\n\n                                <div class=\"aux-overlay-content\">\n                                                                        <div class=\"aux-portfolio-overlay-buttons\">\n                                        <div class=\"aux-hover-circle-plus aux-delay-2x\">\n                                            <a href=\"https:\/\/workmimarlik.com\/wp-content\/uploads\/2022\/12\/photo_2022-11-17_12-42-20.jpg\" data-elementor-open-lightbox = \"no\" data-original-width = \"1280\" data-original-height = \"960\" data-caption = \"photo_2022-11-17_12-42-20\" class=\"aux-lightbox-btn \" >\n                                                <div class=\"aux-arrow-nav aux-round aux-hover-slide aux-outline aux-semi-small aux-white\">\n                                                    <span class=\"aux-overlay\"><\/span>\n                                                    <span class=\"aux-svg-arrow aux-medium-plus aux-white\"><\/span>\n                                                    <span class=\"aux-hover-arrow aux-svg-arrow aux-medium-plus aux-black\"><\/span>\n                                                <\/div>\n                                            <\/a>\n                                        <\/div>\n                                        <div class=\"aux-arrow-post-link aux-hover-circle-link\">\n                                            <a href=\"https:\/\/workmimarlik.com\/tr\/portfolio\/dekoplas-plastik\/\">\n                                                <div class=\"aux-arrow-nav aux-round aux-hover-slide aux-outline aux-semi-small aux-white\">\n                                                    <span class=\"aux-overlay\"><\/span>\n                                                    <span class=\"aux-svg-arrow aux-medium-right aux-white\"><\/span>\n                                                    <span class=\"aux-hover-arrow aux-svg-arrow aux-medium-right aux-black\"><\/span>\n                                                <\/div>\n                                            <\/a>\n                                        <\/div>\n\n                                    <\/div>\n                                                                                                            <div class=\"entry-main\">\n\n                                                                        <header class=\"entry-header\">\n                                        <h3 class=\"entry-title aux-hover-move-up\">\n                                            <a href=\"https:\/\/workmimarlik.com\/tr\/portfolio\/dekoplas-plastik\/\">\n                                                DEKOPLAS PLAST\u0130K                                            <\/a>\n                                        <\/h3>\n                                    <\/header>\n                                                                                                            <div class=\"entry-info aux-hover-move-up aux-delay-1x\">\n                                        <span class=\"entry-tax\">\n                                                                                        <a href=\"https:\/\/workmimarlik.com\/tr\/portfolio-cat\/maxima-fuar-standi\/\" title=\"View all posts in Maxima Fuar Stand\u0131\" rel=\"category\" >Maxima Fuar Stand\u0131<\/a>                                        <\/span>\n                                    <\/div>\n                                                                                                            <\/div>\n                                                                <\/div>\n                        <\/article>\n<\/div><div class=\"aux-iso-item aux-loading aux-col\">                         <article class=\"aux-item-overlay aux-hover-active aux-hover-twoway  post-912 portfolio type-portfolio status-publish has-post-thumbnail hentry portfolio-cat-ahsap-fuar-standi portfolio-tag-uncategorized portfolio-filter-uncategorized\" >\n                                <div class=\"entry-media aux-frame-boxed-darken aux-frame-zoom \">\n                                    <div class=\"aux-media-frame aux-media-image\"><a href=\"https:\/\/workmimarlik.com\/tr\/portfolio\/vela-dekor-2\/\"><img loading=\"lazy\" width=\"606\" height=\"455\" class=\"aux-attachment aux-featured-image attachment-606.66666666667x455 aux-attachment-id-913 \" alt=\"photo_2022-11-17_12-51-56 (2)\" data-ratio=\"1.33\" data-original-w=\"1280\" sizes=\"auto\" data-srcset=\"https:\/\/workmimarlik.com\/wp-content\/uploads\/2022\/12\/photo_2022-11-17_12-51-56-2-150x113.jpg 150w,https:\/\/workmimarlik.com\/wp-content\/uploads\/2022\/12\/photo_2022-11-17_12-51-56-2-300x225.jpg 300w,https:\/\/workmimarlik.com\/wp-content\/uploads\/2022\/12\/photo_2022-11-17_12-51-56-2-768x576.jpg 768w,https:\/\/workmimarlik.com\/wp-content\/uploads\/2022\/12\/photo_2022-11-17_12-51-56-2-1024x768.jpg 1024w,https:\/\/workmimarlik.com\/wp-content\/uploads\/2022\/12\/photo_2022-11-17_12-51-56-2-607x455.jpg 607w,https:\/\/workmimarlik.com\/wp-content\/uploads\/2022\/12\/photo_2022-11-17_12-51-56-2-1270x952.jpg 1270w\" data-src=\"https:\/\/workmimarlik.com\/wp-content\/uploads\/2022\/12\/photo_2022-11-17_12-51-56-2-607x455.jpg\" \/><\/a><\/div>                                <\/div>\n\n                                <div class=\"aux-overlay-content\">\n                                                                        <div class=\"aux-portfolio-overlay-buttons\">\n                                        <div class=\"aux-hover-circle-plus aux-delay-2x\">\n                                            <a href=\"https:\/\/workmimarlik.com\/wp-content\/uploads\/2022\/12\/photo_2022-11-17_12-51-56-2.jpg\" data-elementor-open-lightbox = \"no\" data-original-width = \"1280\" data-original-height = \"960\" data-caption = \"photo_2022-11-17_12-51-56 (2)\" class=\"aux-lightbox-btn \" >\n                                                <div class=\"aux-arrow-nav aux-round aux-hover-slide aux-outline aux-semi-small aux-white\">\n                                                    <span class=\"aux-overlay\"><\/span>\n                                                    <span class=\"aux-svg-arrow aux-medium-plus aux-white\"><\/span>\n                                                    <span class=\"aux-hover-arrow aux-svg-arrow aux-medium-plus aux-black\"><\/span>\n                                                <\/div>\n                                            <\/a>\n                                        <\/div>\n                                        <div class=\"aux-arrow-post-link aux-hover-circle-link\">\n                                            <a href=\"https:\/\/workmimarlik.com\/tr\/portfolio\/vela-dekor-2\/\">\n                                                <div class=\"aux-arrow-nav aux-round aux-hover-slide aux-outline aux-semi-small aux-white\">\n                                                    <span class=\"aux-overlay\"><\/span>\n                                                    <span class=\"aux-svg-arrow aux-medium-right aux-white\"><\/span>\n                                                    <span class=\"aux-hover-arrow aux-svg-arrow aux-medium-right aux-black\"><\/span>\n                                                <\/div>\n                                            <\/a>\n                                        <\/div>\n\n                                    <\/div>\n                                                                                                            <div class=\"entry-main\">\n\n                                                                        <header class=\"entry-header\">\n                                        <h3 class=\"entry-title aux-hover-move-up\">\n                                            <a href=\"https:\/\/workmimarlik.com\/tr\/portfolio\/vela-dekor-2\/\">\n                                                VELA DEKOR                                            <\/a>\n                                        <\/h3>\n                                    <\/header>\n                                                                                                            <div class=\"entry-info aux-hover-move-up aux-delay-1x\">\n                                        <span class=\"entry-tax\">\n                                                                                        <a href=\"https:\/\/workmimarlik.com\/tr\/portfolio-cat\/ahsap-fuar-standi\/\" title=\"View all posts in Ah\u015fap Fuar Stand\u0131\" rel=\"category\" >Ah\u015fap Fuar Stand\u0131<\/a>                                        <\/span>\n                                    <\/div>\n                                                                                                            <\/div>\n                                                                <\/div>\n                        <\/article>\n<\/div><div class=\"aux-iso-item aux-loading aux-col\">                         <article class=\"aux-item-overlay aux-hover-active aux-hover-twoway  post-924 portfolio type-portfolio status-publish has-post-thumbnail hentry portfolio-cat-ahsap-fuar-standi portfolio-tag-uncategorized portfolio-filter-uncategorized\" >\n                                <div class=\"entry-media aux-frame-boxed-darken aux-frame-zoom \">\n                                    <div class=\"aux-media-frame aux-media-image\"><a href=\"https:\/\/workmimarlik.com\/tr\/portfolio\/faran-dekor\/\"><img loading=\"lazy\" width=\"606\" height=\"455\" class=\"aux-attachment aux-featured-image attachment-606.66666666667x455 aux-attachment-id-925 \" alt=\"photo_2022-11-17_12-59-36 (6)\" data-ratio=\"1.33\" data-original-w=\"1280\" sizes=\"auto\" data-srcset=\"https:\/\/workmimarlik.com\/wp-content\/uploads\/2022\/12\/photo_2022-11-17_12-59-36-6-150x113.jpg 150w,https:\/\/workmimarlik.com\/wp-content\/uploads\/2022\/12\/photo_2022-11-17_12-59-36-6-300x225.jpg 300w,https:\/\/workmimarlik.com\/wp-content\/uploads\/2022\/12\/photo_2022-11-17_12-59-36-6-768x576.jpg 768w,https:\/\/workmimarlik.com\/wp-content\/uploads\/2022\/12\/photo_2022-11-17_12-59-36-6-1024x768.jpg 1024w,https:\/\/workmimarlik.com\/wp-content\/uploads\/2022\/12\/photo_2022-11-17_12-59-36-6-607x455.jpg 607w,https:\/\/workmimarlik.com\/wp-content\/uploads\/2022\/12\/photo_2022-11-17_12-59-36-6-1270x952.jpg 1270w\" data-src=\"https:\/\/workmimarlik.com\/wp-content\/uploads\/2022\/12\/photo_2022-11-17_12-59-36-6-607x455.jpg\" \/><\/a><\/div>                                <\/div>\n\n                                <div class=\"aux-overlay-content\">\n                                                                        <div class=\"aux-portfolio-overlay-buttons\">\n                                        <div class=\"aux-hover-circle-plus aux-delay-2x\">\n                                            <a href=\"https:\/\/workmimarlik.com\/wp-content\/uploads\/2022\/12\/photo_2022-11-17_12-59-36-6.jpg\" data-elementor-open-lightbox = \"no\" data-original-width = \"1280\" data-original-height = \"960\" data-caption = \"photo_2022-11-17_12-59-36 (6)\" class=\"aux-lightbox-btn \" >\n                                                <div class=\"aux-arrow-nav aux-round aux-hover-slide aux-outline aux-semi-small aux-white\">\n                                                    <span class=\"aux-overlay\"><\/span>\n                                                    <span class=\"aux-svg-arrow aux-medium-plus aux-white\"><\/span>\n                                                    <span class=\"aux-hover-arrow aux-svg-arrow aux-medium-plus aux-black\"><\/span>\n                                                <\/div>\n                                            <\/a>\n                                        <\/div>\n                                        <div class=\"aux-arrow-post-link aux-hover-circle-link\">\n                                            <a href=\"https:\/\/workmimarlik.com\/tr\/portfolio\/faran-dekor\/\">\n                                                <div class=\"aux-arrow-nav aux-round aux-hover-slide aux-outline aux-semi-small aux-white\">\n                                                    <span class=\"aux-overlay\"><\/span>\n                                                    <span class=\"aux-svg-arrow aux-medium-right aux-white\"><\/span>\n                                                    <span class=\"aux-hover-arrow aux-svg-arrow aux-medium-right aux-black\"><\/span>\n                                                <\/div>\n                                            <\/a>\n                                        <\/div>\n\n                                    <\/div>\n                                                                                                            <div class=\"entry-main\">\n\n                                                                        <header class=\"entry-header\">\n                                        <h3 class=\"entry-title aux-hover-move-up\">\n                                            <a href=\"https:\/\/workmimarlik.com\/tr\/portfolio\/faran-dekor\/\">\n                                                FARAN DEKOR                                            <\/a>\n                                        <\/h3>\n                                    <\/header>\n                                                                                                            <div class=\"entry-info aux-hover-move-up aux-delay-1x\">\n                                        <span class=\"entry-tax\">\n                                                                                        <a href=\"https:\/\/workmimarlik.com\/tr\/portfolio-cat\/ahsap-fuar-standi\/\" title=\"View all posts in Ah\u015fap Fuar Stand\u0131\" rel=\"category\" >Ah\u015fap Fuar Stand\u0131<\/a>                                        <\/span>\n                                    <\/div>\n                                                                                                            <\/div>\n                                                                <\/div>\n                        <\/article>\n<\/div><div class=\"aux-iso-item aux-loading aux-col\">                         <article class=\"aux-item-overlay aux-hover-active aux-hover-twoway  post-936 portfolio type-portfolio status-publish has-post-thumbnail hentry portfolio-cat-ahsap-fuar-standi portfolio-tag-uncategorized portfolio-filter-uncategorized\" >\n                                <div class=\"entry-media aux-frame-boxed-darken aux-frame-zoom \">\n                                    <div class=\"aux-media-frame aux-media-image\"><a href=\"https:\/\/workmimarlik.com\/tr\/portfolio\/sur-kalip\/\"><img loading=\"lazy\" width=\"606\" height=\"455\" class=\"aux-attachment aux-featured-image attachment-606.66666666667x455 aux-attachment-id-937 \" alt=\"photo_2022-11-17_12-43-37\" data-ratio=\"1.33\" data-original-w=\"1280\" sizes=\"auto\" data-srcset=\"https:\/\/workmimarlik.com\/wp-content\/uploads\/2022\/12\/photo_2022-11-17_12-43-37-150x113.jpg 150w,https:\/\/workmimarlik.com\/wp-content\/uploads\/2022\/12\/photo_2022-11-17_12-43-37-300x225.jpg 300w,https:\/\/workmimarlik.com\/wp-content\/uploads\/2022\/12\/photo_2022-11-17_12-43-37-768x576.jpg 768w,https:\/\/workmimarlik.com\/wp-content\/uploads\/2022\/12\/photo_2022-11-17_12-43-37-1024x768.jpg 1024w,https:\/\/workmimarlik.com\/wp-content\/uploads\/2022\/12\/photo_2022-11-17_12-43-37-607x455.jpg 607w,https:\/\/workmimarlik.com\/wp-content\/uploads\/2022\/12\/photo_2022-11-17_12-43-37-1270x952.jpg 1270w\" data-src=\"https:\/\/workmimarlik.com\/wp-content\/uploads\/2022\/12\/photo_2022-11-17_12-43-37-607x455.jpg\" \/><\/a><\/div>                                <\/div>\n\n                                <div class=\"aux-overlay-content\">\n                                                                        <div class=\"aux-portfolio-overlay-buttons\">\n                                        <div class=\"aux-hover-circle-plus aux-delay-2x\">\n                                            <a href=\"https:\/\/workmimarlik.com\/wp-content\/uploads\/2022\/12\/photo_2022-11-17_12-43-37.jpg\" data-elementor-open-lightbox = \"no\" data-original-width = \"1280\" data-original-height = \"1094\" data-caption = \"photo_2022-11-17_12-43-37\" class=\"aux-lightbox-btn \" >\n                                                <div class=\"aux-arrow-nav aux-round aux-hover-slide aux-outline aux-semi-small aux-white\">\n                                                    <span class=\"aux-overlay\"><\/span>\n                                                    <span class=\"aux-svg-arrow aux-medium-plus aux-white\"><\/span>\n                                                    <span class=\"aux-hover-arrow aux-svg-arrow aux-medium-plus aux-black\"><\/span>\n                                                <\/div>\n                                            <\/a>\n                                        <\/div>\n                                        <div class=\"aux-arrow-post-link aux-hover-circle-link\">\n                                            <a href=\"https:\/\/workmimarlik.com\/tr\/portfolio\/sur-kalip\/\">\n                                                <div class=\"aux-arrow-nav aux-round aux-hover-slide aux-outline aux-semi-small aux-white\">\n                                                    <span class=\"aux-overlay\"><\/span>\n                                                    <span class=\"aux-svg-arrow aux-medium-right aux-white\"><\/span>\n                                                    <span class=\"aux-hover-arrow aux-svg-arrow aux-medium-right aux-black\"><\/span>\n                                                <\/div>\n                                            <\/a>\n                                        <\/div>\n\n                                    <\/div>\n                                                                                                            <div class=\"entry-main\">\n\n                                                                        <header class=\"entry-header\">\n                                        <h3 class=\"entry-title aux-hover-move-up\">\n                                            <a href=\"https:\/\/workmimarlik.com\/tr\/portfolio\/sur-kalip\/\">\n                                                SUR KALIP                                            <\/a>\n                                        <\/h3>\n                                    <\/header>\n                                                                                                            <div class=\"entry-info aux-hover-move-up aux-delay-1x\">\n                                        <span class=\"entry-tax\">\n                                                                                        <a href=\"https:\/\/workmimarlik.com\/tr\/portfolio-cat\/ahsap-fuar-standi\/\" title=\"View all posts in Ah\u015fap Fuar Stand\u0131\" rel=\"category\" >Ah\u015fap Fuar Stand\u0131<\/a>                                        <\/span>\n                                    <\/div>\n                                                                                                            <\/div>\n                                                                <\/div>\n                        <\/article>\n<\/div><div class=\"aux-iso-item aux-loading aux-col\">                         <article class=\"aux-item-overlay aux-hover-active aux-hover-twoway  post-946 portfolio type-portfolio status-publish has-post-thumbnail hentry portfolio-cat-ahsap-fuar-standi portfolio-tag-uncategorized portfolio-filter-uncategorized\" >\n                                <div class=\"entry-media aux-frame-boxed-darken aux-frame-zoom \">\n                                    <div class=\"aux-media-frame aux-media-image\"><a href=\"https:\/\/workmimarlik.com\/tr\/portfolio\/tks-makine\/\"><img loading=\"lazy\" width=\"606\" height=\"455\" class=\"aux-attachment aux-featured-image attachment-606.66666666667x455 aux-attachment-id-947 \" alt=\"photo_2022-11-17_12-41-55 (3)\" data-ratio=\"1.33\" data-original-w=\"1280\" sizes=\"auto\" data-srcset=\"https:\/\/workmimarlik.com\/wp-content\/uploads\/2022\/12\/photo_2022-11-17_12-41-55-3-150x113.jpg 150w,https:\/\/workmimarlik.com\/wp-content\/uploads\/2022\/12\/photo_2022-11-17_12-41-55-3-300x225.jpg 300w,https:\/\/workmimarlik.com\/wp-content\/uploads\/2022\/12\/photo_2022-11-17_12-41-55-3-768x576.jpg 768w,https:\/\/workmimarlik.com\/wp-content\/uploads\/2022\/12\/photo_2022-11-17_12-41-55-3-1024x768.jpg 1024w,https:\/\/workmimarlik.com\/wp-content\/uploads\/2022\/12\/photo_2022-11-17_12-41-55-3-607x455.jpg 607w,https:\/\/workmimarlik.com\/wp-content\/uploads\/2022\/12\/photo_2022-11-17_12-41-55-3-1270x952.jpg 1270w\" data-src=\"https:\/\/workmimarlik.com\/wp-content\/uploads\/2022\/12\/photo_2022-11-17_12-41-55-3-607x455.jpg\" \/><\/a><\/div>                                <\/div>\n\n                                <div class=\"aux-overlay-content\">\n                                                                        <div class=\"aux-portfolio-overlay-buttons\">\n                                        <div class=\"aux-hover-circle-plus aux-delay-2x\">\n                                            <a href=\"https:\/\/workmimarlik.com\/wp-content\/uploads\/2022\/12\/photo_2022-11-17_12-41-55-3.jpg\" data-elementor-open-lightbox = \"no\" data-original-width = \"1280\" data-original-height = \"960\" data-caption = \"photo_2022-11-17_12-41-55 (3)\" class=\"aux-lightbox-btn \" >\n                                                <div class=\"aux-arrow-nav aux-round aux-hover-slide aux-outline aux-semi-small aux-white\">\n                                                    <span class=\"aux-overlay\"><\/span>\n                                                    <span class=\"aux-svg-arrow aux-medium-plus aux-white\"><\/span>\n                                                    <span class=\"aux-hover-arrow aux-svg-arrow aux-medium-plus aux-black\"><\/span>\n                                                <\/div>\n                                            <\/a>\n                                        <\/div>\n                                        <div class=\"aux-arrow-post-link aux-hover-circle-link\">\n                                            <a href=\"https:\/\/workmimarlik.com\/tr\/portfolio\/tks-makine\/\">\n                                                <div class=\"aux-arrow-nav aux-round aux-hover-slide aux-outline aux-semi-small aux-white\">\n                                                    <span class=\"aux-overlay\"><\/span>\n                                                    <span class=\"aux-svg-arrow aux-medium-right aux-white\"><\/span>\n                                                    <span class=\"aux-hover-arrow aux-svg-arrow aux-medium-right aux-black\"><\/span>\n                                                <\/div>\n                                            <\/a>\n                                        <\/div>\n\n                                    <\/div>\n                                                                                                            <div class=\"entry-main\">\n\n                                                                        <header class=\"entry-header\">\n                                        <h3 class=\"entry-title aux-hover-move-up\">\n                                            <a href=\"https:\/\/workmimarlik.com\/tr\/portfolio\/tks-makine\/\">\n                                                TKS MAK\u0130NE                                            <\/a>\n                                        <\/h3>\n                                    <\/header>\n                                                                                                            <div class=\"entry-info aux-hover-move-up aux-delay-1x\">\n                                        <span class=\"entry-tax\">\n                                                                                        <a href=\"https:\/\/workmimarlik.com\/tr\/portfolio-cat\/ahsap-fuar-standi\/\" title=\"View all posts in Ah\u015fap Fuar Stand\u0131\" rel=\"category\" >Ah\u015fap Fuar Stand\u0131<\/a>                                        <\/span>\n                                    <\/div>\n                                                                                                            <\/div>\n                                                                <\/div>\n                        <\/article>\n<\/div><div class=\"aux-iso-item aux-loading aux-col\">                         <article class=\"aux-item-overlay aux-hover-active aux-hover-twoway  post-990 portfolio type-portfolio status-publish has-post-thumbnail hentry portfolio-cat-moduler-fuar-standi portfolio-tag-uncategorized portfolio-filter-uncategorized\" >\n                                <div class=\"entry-media aux-frame-boxed-darken aux-frame-zoom \">\n                                    <div class=\"aux-media-frame aux-media-image\"><a href=\"https:\/\/workmimarlik.com\/tr\/portfolio\/imam-riza-dergah-yayinlari\/\"><img loading=\"lazy\" width=\"606\" height=\"455\" class=\"aux-attachment aux-featured-image attachment-606.66666666667x455 aux-attachment-id-991 \" alt=\"WhatsApp Image 2022-12-13 at 15.18.33\" data-ratio=\"1.33\" data-original-w=\"1599\" sizes=\"auto\" data-srcset=\"https:\/\/workmimarlik.com\/wp-content\/uploads\/2022\/12\/WhatsApp-Image-2022-12-13-at-15.18.33-150x113.jpeg 150w,https:\/\/workmimarlik.com\/wp-content\/uploads\/2022\/12\/WhatsApp-Image-2022-12-13-at-15.18.33-300x225.jpeg 300w,https:\/\/workmimarlik.com\/wp-content\/uploads\/2022\/12\/WhatsApp-Image-2022-12-13-at-15.18.33-768x576.jpeg 768w,https:\/\/workmimarlik.com\/wp-content\/uploads\/2022\/12\/WhatsApp-Image-2022-12-13-at-15.18.33-1024x768.jpeg 1024w,https:\/\/workmimarlik.com\/wp-content\/uploads\/2022\/12\/WhatsApp-Image-2022-12-13-at-15.18.33-607x455.jpeg 607w,https:\/\/workmimarlik.com\/wp-content\/uploads\/2022\/12\/WhatsApp-Image-2022-12-13-at-15.18.33-1589x1191.jpeg 1589w\" data-src=\"https:\/\/workmimarlik.com\/wp-content\/uploads\/2022\/12\/WhatsApp-Image-2022-12-13-at-15.18.33-607x455.jpeg\" \/><\/a><\/div>                                <\/div>\n\n                                <div class=\"aux-overlay-content\">\n                                                                        <div class=\"aux-portfolio-overlay-buttons\">\n                                        <div class=\"aux-hover-circle-plus aux-delay-2x\">\n                                            <a href=\"https:\/\/workmimarlik.com\/wp-content\/uploads\/2022\/12\/WhatsApp-Image-2022-12-13-at-15.18.33.jpeg\" data-elementor-open-lightbox = \"no\" data-original-width = \"1599\" data-original-height = \"1200\" data-caption = \"WhatsApp Image 2022-12-13 at 15.18.33\" class=\"aux-lightbox-btn \" >\n                                                <div class=\"aux-arrow-nav aux-round aux-hover-slide aux-outline aux-semi-small aux-white\">\n                                                    <span class=\"aux-overlay\"><\/span>\n                                                    <span class=\"aux-svg-arrow aux-medium-plus aux-white\"><\/span>\n                                                    <span class=\"aux-hover-arrow aux-svg-arrow aux-medium-plus aux-black\"><\/span>\n                                                <\/div>\n                                            <\/a>\n                                        <\/div>\n                                        <div class=\"aux-arrow-post-link aux-hover-circle-link\">\n                                            <a href=\"https:\/\/workmimarlik.com\/tr\/portfolio\/imam-riza-dergah-yayinlari\/\">\n                                                <div class=\"aux-arrow-nav aux-round aux-hover-slide aux-outline aux-semi-small aux-white\">\n                                                    <span class=\"aux-overlay\"><\/span>\n                                                    <span class=\"aux-svg-arrow aux-medium-right aux-white\"><\/span>\n                                                    <span class=\"aux-hover-arrow aux-svg-arrow aux-medium-right aux-black\"><\/span>\n                                                <\/div>\n                                            <\/a>\n                                        <\/div>\n\n                                    <\/div>\n                                                                                                            <div class=\"entry-main\">\n\n                                                                        <header class=\"entry-header\">\n                                        <h3 class=\"entry-title aux-hover-move-up\">\n                                            <a href=\"https:\/\/workmimarlik.com\/tr\/portfolio\/imam-riza-dergah-yayinlari\/\">\n                                                \u0130MAM RIZA DERGAH YAYINLARI                                            <\/a>\n                                        <\/h3>\n                                    <\/header>\n                                                                                                            <div class=\"entry-info aux-hover-move-up aux-delay-1x\">\n                                        <span class=\"entry-tax\">\n                                                                                        <a href=\"https:\/\/workmimarlik.com\/tr\/portfolio-cat\/moduler-fuar-standi\/\" title=\"View all posts in Mod\u00fcler Fuar Stand\u0131\" rel=\"category\" >Mod\u00fcler Fuar Stand\u0131<\/a>                                        <\/span>\n                                    <\/div>\n                                                                                                            <\/div>\n                                                                <\/div>\n                        <\/article>\n<\/div><\/div><script type=\"text\/javascript\">var auabc3e781AjaxConfig = {\"title\":\"\",\"cat\":[\"15\",\"16\",\"18\"],\"num\":100,\"only_posts__in\":\"\",\"include\":\"\",\"exclude\":\"\",\"posts_per_page\":-1,\"offset\":\"\",\"order_by\":\"date\",\"order\":\"ASC\",\"exclude_without_media\":\"yes\",\"display_like\":\"no\",\"deeplink\":\"yes\",\"use_ajax\":\"yes\",\"deeplink_slug\":\"\",\"show_filters\":\"yes\",\"filter_by\":\"portfolio-cat\",\"filter_style\":\"aux-overlay aux-underline-anim\",\"filter_align\":\"aux-center\",\"reveal_transition_duration\":\"600\",\"reveal_between_delay\":\"60\",\"hide_transition_duration\":\"600\",\"hide_between_delay\":\"30\",\"item_style\":\"overlay-lightbox-boxed\",\"tile_style_pattern\":\"default\",\"tiles_item_style\":\"overlay\",\"entry_background_color\":\"\",\"entry_border_color\":\"\",\"paginate\":\"yes\",\"perpage\":1000,\"crop\":true,\"display_title\":\"yes\",\"show_info\":\"yes\",\"display_read_more\":false,\"image_aspect_ratio\":\"0.75\",\"space\":\"30\",\"desktop_cnum\":\"3\",\"tablet_cnum\":\"2\",\"phone_cnum\":\"1\",\"layout\":\"grid\",\"tag\":\"\",\"filter\":\"\",\"extra_classes\":\"\",\"extra_column_classes\":\"\",\"custom_el_id\":\"\",\"template_part_file\":\"recent-portfolio\",\"extra_template_path\":\"\\\/home\\\/u191629506\\\/domains\\\/workmimarlik.com\\\/public_html\\\/wp-content\\\/plugins\\\/auxin-portfolio\\\/public\\\/templates\\\/elements\",\"universal_id\":\"auabc3e781\",\"query_args\":[],\"term\":\"\",\"reset_query\":true,\"use_wp_query\":false,\"wp_query_args\":[],\"custom_wp_query\":\"\",\"loadmore_type\":null,\"loadmore_label\":null,\"loadmore_per_page\":100,\"term_field\":\"slug\",\"base\":\"aux_recent_portfolios_grid\",\"base_class\":\"aux-widget-recent-portfolios\",\"paged\":\"\",\"override_global_query\":false,\"content\":null,\"skip_wrappers\":false,\"content_width\":2000,\"inview_transition\":\"none\",\"inview_duration\":\"\",\"inview_delay\":\"\",\"inview_repeat\":\"no\",\"inview_offset\":\"\",\"called_from\":\"elementor\"};<\/script><\/section><!-- widget-container -->\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-756fcbe5 elementor-section-stretched elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"756fcbe5\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;stretch_section&quot;:&quot;section-stretched&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"aux-parallax-section elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-2509b081\" data-id=\"2509b081\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c8e92b aux-appear-watch-animation aux-scale-down elementor-widget elementor-widget-aux_modern_heading\" data-id=\"c8e92b\" data-element_type=\"widget\" data-widget_type=\"aux_modern_heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<section class=\"aux-widget-modern-heading\">\n            <div class=\"aux-widget-inner\"><h2 class=\"aux-modern-heading-primary\">Bizimle \u00e7al\u0131\u015fmak ister misiniz?<\/h2><div class=\"aux-modern-heading-description\"><p>Bizimle \u00e7al\u0131\u015fmak, ailemizin bir par\u00e7as\u0131 ve ihtiya\u00e7lar\u0131n\u0131za \u00f6zel \u00e7\u00f6z\u00fcmler \u00fcretmemiz i\u00e7in diledi\u011finiz zaman bizimle ileti\u015fime ge\u00e7ebilir ve detayl\u0131 bilgi alabilirsiniz.<\/p><\/div><\/div>\n        <\/section>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9291135 elementor-widget elementor-widget-aux_modern_button\" data-id=\"9291135\" data-element_type=\"widget\" data-widget_type=\"aux_modern_button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t    <div class=\"aux-modern-button-wrapper aux-modern-button-align-center\" >\n                    <a class=\"aux-modern-button aux-white aux-modern-button-xl aux-modern-button-normal aux-modern-button-default aux-icon-right\" href=\"\/iletisim\">\n                <div class=\"aux-overlay\"><\/div>\n                                    <div class=\"aux-icon \">\n                        <i aria-hidden=\"true\" class=\"auxicon2 auxicon2-arrow-chevron-small-right\"><\/i>                    <\/div>\n                                <div class=\"aux-text\">\n<span class=\"aux-text-before\">\u0130LET\u0130\u015e\u0130ME GE\u00c7<\/span>                <\/div>\n            <\/a>\n            \n    <\/div>\n\n    \t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Projelerimiz WORK M\u0130MARLIK Tamamlanan Projelerimiz Referanslar\u0131m\u0131z\u0131n aras\u0131na kat\u0131lmak ve onlarca ba\u015far\u0131l\u0131 projeden birine sahip olmak i\u00e7in bizimle ileti\u015fime ge\u00e7ebilirsiniz. All Ah\u015fap Fuar Stand\u0131 Maxima Fuar Stand\u0131 Mod\u00fcler Fuar Stand\u0131 Gapsan Pazarlama Ah\u015fap Fuar Stand\u0131 Vela Dekor Ah\u015fap Fuar Stand\u0131 AKKO Ah\u015fap Fuar Stand\u0131 ARERKO Ah\u015fap Fuar Stand\u0131 ERSOY PANO Ah\u015fap Fuar Stand\u0131 HAKAN OTOMOT\u0130V Maxima [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-69","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/workmimarlik.com\/tr\/wp-json\/wp\/v2\/pages\/69","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/workmimarlik.com\/tr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/workmimarlik.com\/tr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/workmimarlik.com\/tr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/workmimarlik.com\/tr\/wp-json\/wp\/v2\/comments?post=69"}],"version-history":[{"count":47,"href":"https:\/\/workmimarlik.com\/tr\/wp-json\/wp\/v2\/pages\/69\/revisions"}],"predecessor-version":[{"id":1010,"href":"https:\/\/workmimarlik.com\/tr\/wp-json\/wp\/v2\/pages\/69\/revisions\/1010"}],"wp:attachment":[{"href":"https:\/\/workmimarlik.com\/tr\/wp-json\/wp\/v2\/media?parent=69"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}